{"id":11973,"date":"2025-09-25T18:06:00","date_gmt":"2025-09-25T16:06:00","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=11973"},"modified":"2025-10-16T12:43:05","modified_gmt":"2025-10-16T10:43:05","slug":"recolte-de-pommes-de-terre-2025-pas-terrible-pas-terrible","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2025\/09\/25\/recolte-de-pommes-de-terre-2025-pas-terrible-pas-terrible\/","title":{"rendered":"R\u00e9colte de pommes de terre 2025: pas terrible, pas terrible&#8230;"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-acdc2be3337f17bda160194793961091 wp-block-paragraph\">\u00c9tant donn\u00e9 la s\u00e9cheresse de cet \u00e9t\u00e9 (seulement 10 journ\u00e9es de pluies \u00e9pisodiques \u00e0 la fin juillet, avec en tout 110 millim\u00e8tres), je m&rsquo;attendais \u00e0 une r\u00e9colte assez mis\u00e9rable pour les pommes de terre dites \u00ab\u00a0de conservation\u00a0\u00bb . Elle n&rsquo;a \u00e9t\u00e9 que mauvaise (environ 25 kilos, dont une dizaine ont \u00e9t\u00e9 r\u00e9colt\u00e9s au fur et \u00e0 mesure durant l&rsquo;\u00e9t\u00e9), c&rsquo;est d\u00e9j\u00e0 mieux que rien.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-a178324ccd162236480db2641e1da526 wp-block-paragraph\">D&rsquo;apr\u00e8s mes discussions avec les jardiniers des environs, qui ont connu des d\u00e9convenues similaires (m\u00eame les plus exp\u00e9riment\u00e9s), cela tient principalement \u00e0 la s\u00e9cheresse et aux deux vagues de chaleur de juin et de d\u00e9but ao\u00fbt. Tr\u00e8s pris par de gros chantiers sur le terrain et dans ma maison, j&rsquo;ai n\u00e9glig\u00e9 d&rsquo;arroser, et cela a atrophi\u00e9 largement la croissance de ces plants, et surtout des jeunes tubercules.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/09\/Pommes-de-terre-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1001\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/09\/Pommes-de-terre-1.jpg\" alt=\"\" class=\"wp-image-12859\" style=\"width:372px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/09\/Pommes-de-terre-1.jpg 1000w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/09\/Pommes-de-terre-1-300x300.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/09\/Pommes-de-terre-1-150x150.jpg 150w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/09\/Pommes-de-terre-1-768x769.jpg 768w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/09\/Pommes-de-terre-1-619x620.jpg 619w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/09\/Pommes-de-terre-1-600x601.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/09\/Pommes-de-terre-1-400x400.jpg 400w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-6106f796ffa3e0b7c5296315f932e27a wp-block-paragraph\">D&rsquo;ailleurs les plants qui se sont le mieux d\u00e9velopp\u00e9s sont issus de pommes de terre oubli\u00e9es l&rsquo;ann\u00e9e derni\u00e8re&nbsp;: plus profond\u00e9ment enfouis, ayant entam\u00e9 leur croissance plus t\u00f4t, ils ont pu mieux s&rsquo;enraciner et aller chercher de l&rsquo;humidit\u00e9 plus en profondeur&nbsp;: ces plants l\u00e0 ont donn\u00e9 de tr\u00e8s belles pommes de terre \u00ab\u00a0primeur\u00a0\u00bb. Cette ann\u00e9e je vais tenter un truc: semer des pommes de terre \u00e0 l&rsquo;automne, et pailler g\u00e9n\u00e9reusement, et voir ce que \u00e7a donne.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-858aca73715c52dfef0435006d71d699 wp-block-paragraph\">Si je compte le co\u00fbt des plants, ainsi que le temps et l&rsquo;\u00e9nergie que j&rsquo;ai pass\u00e9 \u00e0 pr\u00e9parer le sol, \u00e0 le semer, puis \u00e0 r\u00e9colter, toujours les genoux dans la terre (et toujours \u00e0 reculons), le rendement de cette culture de pommes de terre est franchement minable. Je n&rsquo;ai pas \u00e9t\u00e9 pay\u00e9 en retour pour mes efforts, c&rsquo;est le moins que l&rsquo;on puisse dire. Un jour sans doute, une r\u00e9colte aussi faible sera une catastrophe, mais pour l&rsquo;instant cela ne pr\u00eate pas \u00e0 cons\u00e9quence&nbsp;: ce n&rsquo;est qu&rsquo;une exp\u00e9rience dont je tiendrai compte les ann\u00e9es prochaines.<\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID11973\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"11973\"\n         id=\"da-reactions-slot-post-11973\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9tant donn\u00e9 la s\u00e9cheresse de cet \u00e9t\u00e9 (seulement 10 journ\u00e9es de pluies \u00e9pisodiques \u00e0 la fin juillet, avec en tout 110 millim\u00e8tres), je m&rsquo;attendais \u00e0 une r\u00e9colte assez mis\u00e9rable pour&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2025\/09\/25\/recolte-de-pommes-de-terre-2025-pas-terrible-pas-terrible\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">R\u00e9colte de pommes de terre 2025: pas terrible, pas terrible&#8230;<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID11973\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"11973\"\n         id=\"da-reactions-slot-post-11973\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":12067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[71,651],"class_list":["post-11973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jardin","tag-jardin","tag-legumes"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/11973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=11973"}],"version-history":[{"count":12,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/11973\/revisions"}],"predecessor-version":[{"id":12860,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/11973\/revisions\/12860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/12067"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=11973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=11973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=11973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}