{"id":1252,"date":"2024-02-21T01:13:16","date_gmt":"2024-02-21T00:13:16","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=1252"},"modified":"2025-03-03T11:48:13","modified_gmt":"2025-03-03T10:48:13","slug":"mgmt-time-to-pretend","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2024\/02\/21\/mgmt-time-to-pretend\/","title":{"rendered":"MGMT &#8211; \u00ab\u00a0Time to pretend\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cet apr\u00e8s-midi j&rsquo;ai partag\u00e9 une punchline qu&rsquo;un de mes neveux a un jour jet\u00e9e \u00e0 mon p\u00e8re: \u00ab\u00a0<em>Tu vois papi, dans l&rsquo;histoire, y&rsquo;a eu d&rsquo;abord l&rsquo;\u00e9poque des dinosaures, ensuite y&rsquo;a eu la tienne\u2026 et maintenant y&rsquo;a la mienne<\/em>\u00a0\u00bb .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette formule m&rsquo;amuse beaucoup, mais elle m&rsquo;a aussi pas mal r\u00e9fl\u00e9chir sur l&rsquo;esp\u00e8ce d&rsquo;arrogance qu&rsquo;il faut sans doute aux jeunes g\u00e9n\u00e9rations pour prendre leur place, en tous cas pour essayer de s&rsquo;en am\u00e9nager une si celles et ceux qui l&rsquo;occupent s&rsquo;y accrochent comme des moules \u00e0 leur rocher.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces derni\u00e8res ann\u00e9es, je suis de plus en plus touch\u00e9 et m\u00eame admiratif quand je vois des jeunes gens, surtout si ce sont des jeunes femmes, et plus encore si ce sont mes enfants, explorer leur propre voie et se lancer dans des projets ambitieux \u2013 et surtout dans <em>leurs<\/em> projets, bas\u00e9s sur <em>leurs<\/em> envies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Allez-y les jeunes, pr\u00e9tendez, avec respect, avec humilit\u00e9, mais sans timidit\u00e9 excessive non plus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bousculer et revendiquer, c&rsquo;est ce que fait ici, avec d\u00e9termination et brio, ce groupe venu de Brooklin. Contrairement \u00e0 la rumeur, MGMT n&rsquo;est pas l&rsquo;acronyme de \u00ab\u00a0Make Great Music Today\u00a0\u00bb , mais le groupe en propose bel et bien une excellente, tr\u00e8s influenc\u00e9e par le rock psych\u00e9d\u00e9lique et la synthpop, enthousiaste et entra\u00eenante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Issue de \u00ab\u00a0Oracular spectacular\u00a0\u00bb , le premier album de MGMT (2007), \u00ab\u00a0Time to pretend\u00a0\u00bb affirme un d\u00e9sir farouche d&rsquo;aller droit au but et de rechercher le succ\u00e8s (\u00ab\u00a0<em>Let&rsquo;s make some music, let&rsquo;s make some money<\/em>\u00a0\u00bb ), de vivre de fa\u00e7on libre et sauvage (\u00ab\u00a0<em>I&rsquo;m feelin&rsquo; rough, I&rsquo;m feeling raw<\/em>\u00a0\u00bb ), quitte \u00e0 ce que \u00e7a ne dure peut-\u00eatre pas tr\u00e8s longtemps (\u00ab\u00a0<em>This is our decision to live fast and die young<\/em>\u00a0\u00bb ). Oui, bien s\u00fbr, c&rsquo;est provocateur, c&rsquo;est cynique, et ce n&rsquo;est pas tr\u00e8s responsable\u2026 Mais la soci\u00e9t\u00e9 qui voudrait formater ses jeunes pour en faire de bons petits producteurs et consommateurs, vaut-elle mieux? En tous cas elle n&rsquo;inspire aux membres de MGMT que de la fatigue ou du m\u00e9pris: \u00ab\u00a0<em>Yeah, it&rsquo;s overwhelming, but what else can we do? \/ Get jobs in offices and wake up for the morning commute?<\/em>\u00a0\u00bb ).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et de toutes fa\u00e7ons c&rsquo;est plus fort qu&rsquo;eux: la jeunesse press\u00e9e que chante MGMT sait que plein de choses de sa vie confortable vont lui manquer (ses parents, ses fr\u00e8res et s\u0153urs, son chien, sa chambre, et m\u00eame l&rsquo;ennui de ses ann\u00e9es d&rsquo;adolescence), mais il n&rsquo;y a rien \u00e0 faire d&rsquo;autre pour elle que de vivre vite et fort.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Musicalement, le morceau se d\u00e9ploie de fa\u00e7on inflexible, \u00e9cartant tout sur son passage tel un bulldozer monstrueux, soutenu par une basse qui vibre tant qu&rsquo;on pourrait croire qu&rsquo;il y a un faux-contact dans les enceintes, parsem\u00e9 de nombreux arrangements qui scintillent et tournoient avec entrain, et travers\u00e9 tout du long par un petit gimmick de synth\u00e9 reconnaissable entre mille et sur lequel le morceau se conclut brutalement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 chaque fin de couplet, la mont\u00e9e en puissance est impressionnante, comme si le groupe voulait s&rsquo;arracher \u00e0 la pesanteur. Tout cela donne furieusement la patate, ainsi que l&rsquo;impression qu&rsquo;il ne s&rsquo;agit pas vraiment d&rsquo;une chanson, mais plut\u00f4t d&rsquo;une revendication lanc\u00e9e le poing lev\u00e9, la t\u00eate haute et le regard fier. \u00c7a me donne aussi, je dois bien l&rsquo;avouer, le regret de ne pas avoir, moi aussi, ru\u00e9 dans les brancards pour m&rsquo;imposer tel que j&rsquo;\u00e9tais, au lieu de faire du ski nautique derri\u00e8re le hors-bord que mon p\u00e8re conduisait pour m&#8217;emmener l\u00e0 o\u00f9 il pensait que je devais aller.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fiers, ambitieux et audacieux, c&rsquo;est ainsi que j&rsquo;aime voir mes enfants, c&rsquo;est ainsi que j&rsquo;ai envie qu&rsquo;ils soient, et tant pis pour moi si \u00e7a me bouscule (ou non, c&rsquo;est tant mieux pour moi, en fait!). Outre la p\u00eache d&rsquo;enfer qui se d\u00e9gage de sa musique, c&rsquo;est sans doute l&rsquo;une des raisons pour lesquelles j&rsquo;aime tant cet hymne g\u00e9n\u00e9rationnel tonitruant qu&rsquo;est \u00ab\u00a0Time to pretend\u00a0\u00bb .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Life can always start up anew\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"MGMT - Time to Pretend (Official HD Video)\" width=\"1230\" height=\"692\" src=\"https:\/\/www.youtube.com\/embed\/B9dSYgd5Elk?list=OLAK5uy_kN24ZHnMBZNDvKNvFIE-WUYPZt1zdxW1Q\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID1252\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"1252\"\n         id=\"da-reactions-slot-post-1252\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cet apr\u00e8s-midi j&rsquo;ai partag\u00e9 une punchline qu&rsquo;un de mes neveux a un jour jet\u00e9e \u00e0 mon p\u00e8re: \u00ab\u00a0Tu vois papi, dans l&rsquo;histoire, y&rsquo;a eu d&rsquo;abord l&rsquo;\u00e9poque des dinosaures, ensuite y&rsquo;a&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2024\/02\/21\/mgmt-time-to-pretend\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">MGMT &#8211; \u00ab\u00a0Time to pretend\u00a0\u00bb<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID1252\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"1252\"\n         id=\"da-reactions-slot-post-1252\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":1253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[20,480,9],"class_list":["post-1252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musique","tag-inde","tag-jeunesse","tag-pop"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/1252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=1252"}],"version-history":[{"count":2,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/1252\/revisions"}],"predecessor-version":[{"id":6373,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/1252\/revisions\/6373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/1253"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=1252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=1252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=1252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}