{"id":12626,"date":"2025-10-10T09:14:12","date_gmt":"2025-10-10T07:14:12","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=12626"},"modified":"2025-10-11T19:53:44","modified_gmt":"2025-10-11T17:53:44","slug":"12626","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2025\/10\/10\/12626\/","title":{"rendered":"150 photos in\u00e9dites de Jean-Louis Murat dans un magnifique livre du photographe Frank Loriou"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-a1e84bd753a29cf94163ce8ab5a022e8 wp-block-paragraph\">Le photographe Frank Loriou vient tout juste de publier un recueil sur <a href=\"https:\/\/gregoryderville.com\/index.php\/tag\/murat\/\" data-type=\"link\" data-id=\"https:\/\/gregoryderville.com\/index.php\/tag\/murat\/\">Jean-Louis Murat<\/a>, intitul\u00e9 <em>Photorama<\/em>, avec plus de 150 images du chanteur auvergnat, pour la plupart in\u00e9dites. Il avait sign\u00e9 pour lui neuf pochettes d&rsquo;albums (dont le magnifique \u00ab\u00a0Mustango\u00a0\u00bb) et r\u00e9alis\u00e9 de nombreuses sessions photos, souvent dans l&rsquo;Auvergne natale de Jean-Louis Murat, sur ses terres \u00e0 Orcival et Douharesse, et toujours en argentique.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama.jpg\" alt=\"\" class=\"wp-image-12629\" style=\"width:352px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama.jpg 800w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-300x300.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-150x150.jpg 150w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-768x768.jpg 768w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-620x620.jpg 620w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-600x600.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-400x400.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-ca84d86f886ec7a00c07dba3417979aa wp-block-paragraph\">Dans le texte introductif, intitul\u00e9 \u00ab\u00a0Je me souviens\u00a0\u00bb, Frank Loriou commente ainsi cette photo, prise dans la cuisine d&rsquo;\u00c9mile, un voisin du po\u00e8te bougon et m\u00e9lancolique\u00a0: \u00ab\u00a0<em>Jean-Louis Murat nous accueillit en grommelant, mi-bourru, mi-amus\u00e9, tel que je le verrais si souvent. La pi\u00e8ce \u00e9tait simple, rustique, mais coquette. Une grande chemin\u00e9e de pierre. Une table devant la fen\u00eatre. Une cuisine ouverte, un peu \u00e0 l&rsquo;\u00e9cart. Un buffet auvergnat, robuste, massif, dans lequel \u00e9tait rang\u00e9e la vaisselle. Rien d&rsquo;ostentatoire. Rien de superflu. La maison d\u2019un paysan, d&rsquo;un ouvrier. D&rsquo;un artisan. D&rsquo;un travailleur<\/em>.\u00a0\u00bb<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2682ab7adbdfc05dc065601fadbd1ea5 wp-block-paragraph\">En voyant cette photo et en lisant cette description respectueuse, je me sens tr\u00e8s touch\u00e9 de savoir que l&rsquo;un de mes chanteurs pr\u00e9f\u00e9r\u00e9s, dont j&rsquo;admire tant la sensibilit\u00e9, l&rsquo;amour fervent de la nature sauvage, la plume splendide et la voix chaleureuse et sensuelle, a pass\u00e9 du temps dans cette cuisine telle qu&rsquo;il y en a tant dans les \u00ab\u00a0<a href=\"https:\/\/gregoryderville.com\/index.php\/2023\/08\/31\/jean-louis-murat-terres-de-france\/\" data-type=\"link\" data-id=\"https:\/\/gregoryderville.com\/index.php\/2023\/08\/31\/jean-louis-murat-terres-de-france\/\">Terres de France<\/a>\u00a0\u00bb qu&rsquo;il aimait chanter, qui ressemble \u00e0 celle de certains de mes voisins limousins, et qui me rappelle aussi celle de ma m\u00e9m\u00e9 de Villers. C&rsquo;est une cuisine qui a v\u00e9cu, mais qui ne se la raconte pas, alors qu&rsquo;elle aurait pourtant bien des choses \u00e0 raconter, justement. Dans cette pi\u00e8ce je reconnais bien mon Jean-Louis&nbsp;: elle est \u00e0 son image, simple, un peu aust\u00e8re, sans esbroufe, d\u00e9daigneuse de toute fantaisie et de toute pr\u00e9tention \u00e0 la modernit\u00e9. \u00c0 l&rsquo;image d&rsquo;un homme qui a essay\u00e9 de vivre de fa\u00e7on d\u00e9cente dans un monde inhospitalier, et qui pour y parvenir a eu besoin de s&rsquo;immerger dans les \u00e9l\u00e9ments, la terre, le vent, la pluie, la neige, le vivant partout autour de lui, et le feu de la chemin\u00e9e.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-ae715a2c305545eb9adae085b09d2d7e wp-block-paragraph\">Frank Loriou, <em>Photorama<\/em>, \u00e9ditions Le Boulon, 204 pages.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" data-id=\"12630\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-1.jpg\" alt=\"\" class=\"wp-image-12630\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-1.jpg 500w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-1-300x150.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-1-400x200.jpg 400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"250\" data-id=\"12631\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-2.jpg\" alt=\"\" class=\"wp-image-12631\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-2.jpg 500w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-2-300x150.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/10\/Jean-Louis-Murat-Photorama-2-400x200.jpg 400w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID12626\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"12626\"\n         id=\"da-reactions-slot-post-12626\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le photographe Frank Loriou vient tout juste de publier un recueil sur Jean-Louis Murat, intitul\u00e9 Photorama, avec plus de 150 images du chanteur auvergnat, pour la plupart in\u00e9dites. Il avait&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2025\/10\/10\/12626\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">150 photos in\u00e9dites de Jean-Louis Murat dans un magnifique livre du photographe Frank Loriou<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID12626\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"12626\"\n         id=\"da-reactions-slot-post-12626\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":12627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[739,81],"tags":[17,203],"class_list":["post-12626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-livres","category-musique","tag-chanson-francaise","tag-murat"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/12626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=12626"}],"version-history":[{"count":6,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/12626\/revisions"}],"predecessor-version":[{"id":12672,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/12626\/revisions\/12672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/12627"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=12626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=12626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=12626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}