{"id":1295,"date":"2024-02-01T01:40:57","date_gmt":"2024-02-01T00:40:57","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=1295"},"modified":"2025-05-17T08:51:38","modified_gmt":"2025-05-17T06:51:38","slug":"the-jesus-and-mary-chain-just-like-honey","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2024\/02\/01\/the-jesus-and-mary-chain-just-like-honey\/","title":{"rendered":"The Jesus and Mary chain &#8211; \u00ab\u00a0Just like honey\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Jesus and Mary chain est un groupe form\u00e9 en 1984 par deux fr\u00e8res, William et Jim Reid, qui sont n\u00e9s et ont grandi \u00e0 Glasgow, et qui ont d\u00e9cid\u00e9 de se lancer dans la musique alors qu&rsquo;ils \u00e9taient tous les deux au ch\u00f4mage depuis plusieurs ann\u00e9es \u2013 la musique comme \u00e9chappatoire \u00e0 une vie remplie de gal\u00e8res, comme pour beaucoup de jeunes issus des cat\u00e9gories populaires dans l&rsquo;Angleterre des ann\u00e9es Thatcher.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00eame si ce n&rsquo;est pas du punk \u00e0 proprement parler (le chanteur ne s&rsquo;\u00e9gosille pas, les m\u00e9lodies sont en g\u00e9n\u00e9ral lentes assez lentes\u2026), l&rsquo;esprit dans lequel The Jesus and Mary chain compose, joue de la musique et g\u00e8re sa carri\u00e8re, mais aussi la personnalit\u00e9 et le comportement de ses membres, y font quand m\u00eame fortement penser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par exemple, les fr\u00e8res Reid sont farouchement attach\u00e9s au fait d&rsquo;aller \u00e0 contre-courant, quitte \u00e0 choquer ou \u00e0 risquer l&rsquo;insucc\u00e8s. Au milieu des ann\u00e9es 80, la sc\u00e8ne musicale est domin\u00e9e par l&rsquo;\u00e9lectro-pop et la new wave, mais eux se disent compl\u00e8tement allergiques aux synth\u00e9tiseurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour ce qui est des paroles, on est dans un m&rsquo;en-foutisme totalement assum\u00e9: le vocabulaire est tr\u00e8s pauvre, la plupart des mots ne comptent qu&rsquo;une syllabe (par exemple you, me, girl, good, love, thing, drug\u2026), et les chansons sont truff\u00e9es d&rsquo;onomatop\u00e9es telles que \u00ab\u00a0yeah\u00a0\u00bb . Il faut dire que les sujets abord\u00e9s ne brillent pas par leur originalit\u00e9 et refl\u00e8tent uniquement ou presque les principales pr\u00e9occupations des ados attard\u00e9s qu&rsquo;\u00e9taient les fr\u00e8res Reid: les filles, la d\u00e9fonce, le sexe, avec en toile de fond un ennui insondable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quant \u00e0 la technique musicale des membres du groupe, elle est elle aussi fort rudimentaire. Le bassiste jouait avec un instrument sur lequel n&rsquo;\u00e9taient install\u00e9es que trois cordes, puis seulement deux, et il a un jour expliqu\u00e9 son choix avec cette formule tr\u00e8s punk dans l&rsquo;\u00e2me: \u00ab\u00a0<em>Pourquoi je mettrais quatre cordes alors que je me sers que de deux? Ce serait d\u00e9penser de l&rsquo;argent pour rien<\/em>.\u00a0\u00bb Pour sa part, le batteur Bobby Gillepsie est entr\u00e9 dans le groupe alors qu&rsquo;il n&rsquo;en avait jamais jou\u00e9 de sa vie, ce qui manifestement n&rsquo;a pas pos\u00e9 de probl\u00e8me, et il a jou\u00e9 debout en se contentant de taper sur deux toms.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et puis il y a les prestations sc\u00e9niques de the Jesus and Mary chain, souvent navrantes et irrespectueuses pour le public: souvent \u00e7a se r\u00e9sumait \u00e0 deux chansons pleines de distorsion et de larsen, parfois le groupe jouait dos au public, et il est m\u00eame arriv\u00e9 que le chanteur mette des coups de pieds dans son micro pour le balancer dans la tronche des personnes install\u00e9es au premier rang. \u00c0 mon avis tout \u00e7a rel\u00e8ve plut\u00f4t de l&rsquo;agression sonore que de la musique, en tous cas je ne suis pas assez masochiste pour m&rsquo;infliger ce genre d&rsquo;\u00e9preuve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quand on ajoute le fait que les fr\u00e8res Reid aimaient bien la baston, avaient l&rsquo;habitude de d\u00e9truire leurs instruments sur sc\u00e8ne, ont eu moult probl\u00e8mes de drogue et avaient un penchant pour la provocation gratuite (ils ont par exemple intitul\u00e9 un morceau \u00ab\u00a0Jesus sucks\u00a0\u00bb ), on se dit que the Jesus and Mary chain est un groupe tr\u00e8s inspir\u00e9 par l&rsquo;esprit punk et son go\u00fbt pour le \u00ab\u00a0rien \u00e0 foutre\u00a0\u00bb .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sorti en 1985 apr\u00e8s quelques mois de concerts qui ont aliment\u00e9 une v\u00e9ritable hype dans le monde du rock ind\u00e9, le premier album du groupe, \u00ab\u00a0Psychocandy\u00a0\u00bb a tout de suite \u00e9t\u00e9 re\u00e7u avec enthousiasme par la critique musicale. On y trouve un m\u00e9lange des deux grandes influences musicales des fr\u00e8res Reid, \u00e0 savoir le son brut et distordu des guitares du Velvet Underground ou des Stooges et les m\u00e9lodies sucr\u00e9es de la pop des ann\u00e9es 60, notamment celle des Beach boys ou des Ronettes. \u00ab\u00a0Psychocandy\u00a0\u00bb est aujourd&rsquo;hui consid\u00e9r\u00e9 comme pr\u00e9curseur de la noisy pop qui explosera au d\u00e9but des ann\u00e9es 90 avec des groupes anglais tels que My bloody Valentine ou Ride.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 vrai dire je n&rsquo;aime pas trop \u00e9couter cet album, car sur la dur\u00e9e \u00e7a m&rsquo;assourdit un peu les tympans (comme dit quelqu&rsquo;un qui se reconna\u00eetra, \u00ab\u00a0not my cup of tea\u00a0\u00bb ). Si vous n&rsquo;aimez pas les guitares satur\u00e9es et les murs de bruit, les sons crus, sales et agressifs, je ne vous conseille pas forc\u00e9ment de tenter l&rsquo;exp\u00e9rience. Il y en a pour penser que la musique de The Jesus and Mary chain est parfaite pour illustrer un film d&rsquo;horreur, et \u00e7a en dit assez long, je crois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais il y a sur ce disque un petit bijou, la chanson d&rsquo;ouverture intitul\u00e9e \u00ab\u00a0Just like honey\u00a0\u00bb . L\u00e0 aussi ce n&rsquo;est pas sp\u00e9cialement recherch\u00e9: un th\u00e8me tr\u00e8s banal (un amour obsessionnel), des paroles simplissimes et sulfureuses (\u00ab\u00a0<em>I&rsquo;ll be your plastic toy \/ for you<\/em>\u00a0\u00bb ), un rythme et une nappe de sons on ne peut plus basiques, une voix lointaine et un peu caverneuse\u2026 A priori il n&rsquo;y a rien l\u00e0 dedans qui devrait attirer mon attention, et pourtant \u00e7a marche: cette chanson a quelque chose d&rsquo;obs\u00e9dant et de l\u00e9g\u00e8rement hypnotique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sofia Coppola ne s&rsquo;y est pas tromp\u00e9e, puisqu&rsquo;elle a choisi d&rsquo;utiliser \u00ab\u00a0Just like honey\u00a0\u00bb dans son superbe film \u00ab\u00a0<a href=\"https:\/\/gregoryderville.com\/index.php\/2020\/11\/24\/air-alone-in-kyoto\/\" data-type=\"link\" data-id=\"https:\/\/gregoryderville.com\/index.php\/2020\/11\/24\/air-alone-in-kyoto\/\">Lost in translation<\/a>\u00a0\u00bb , lui aussi assez sombre et d\u00e9sabus\u00e9. Dans la sc\u00e8ne finale, Bill Murray murmure \u00e0 l&rsquo;oreille de Scarlett Johansson quelques mots dont on n&rsquo;aura jamais le secret, et apr\u00e8s un baiser furtif ils s&rsquo;\u00e9loignent l&rsquo;un de l&rsquo;autre, sans qu&rsquo;on sache s&rsquo;ils se reverront un jour, pendant que nous entendons cette chanson qui d\u00e9borde sur le g\u00e9n\u00e9rique\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The Jesus And Mary Chain - Just Like Honey (Official Music Video)\" width=\"1230\" height=\"923\" src=\"https:\/\/www.youtube.com\/embed\/7EgB__YratE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID1295\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"1295\"\n         id=\"da-reactions-slot-post-1295\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>The Jesus and Mary chain est un groupe form\u00e9 en 1984 par deux fr\u00e8res, William et Jim Reid, qui sont n\u00e9s et ont grandi \u00e0 Glasgow, et qui ont d\u00e9cid\u00e9&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2024\/02\/01\/the-jesus-and-mary-chain-just-like-honey\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">The Jesus and Mary chain &#8211; \u00ab\u00a0Just like honey\u00a0\u00bb<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID1295\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"1295\"\n         id=\"da-reactions-slot-post-1295\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":1296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[13,777,20,9,195],"class_list":["post-1295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musique","tag-angleterre","tag-artiste-a-decouvrir","tag-inde","tag-pop","tag-punk"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/1295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=1295"}],"version-history":[{"count":5,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/1295\/revisions"}],"predecessor-version":[{"id":9494,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/1295\/revisions\/9494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/1296"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=1295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=1295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=1295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}