{"id":1338,"date":"2024-01-15T02:05:23","date_gmt":"2024-01-15T01:05:23","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=1338"},"modified":"2025-03-02T19:16:10","modified_gmt":"2025-03-02T18:16:10","slug":"gerard-manset-avant-lexil","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2024\/01\/15\/gerard-manset-avant-lexil\/","title":{"rendered":"G\u00e9rard Manset &#8211; \u00ab\u00a0Avant l&rsquo;exil\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sortie en 1989 sur son quatorzi\u00e8me album \u00ab\u00a0Matrice\u00a0\u00bb , \u00ab\u00a0Avant l&rsquo;exil\u00a0\u00bb est l&rsquo;une de mes chansons pr\u00e9f\u00e9r\u00e9es de G\u00e9rard Manset, parce que la th\u00e9matique qu&rsquo;elle aborde (les s\u00e9parations) m&rsquo;a toujours \u00e9norm\u00e9ment secou\u00e9, mais aussi pour la vigueur s\u00e8che et nerveuse des guitares, pour sa construction impeccable, pour la mont\u00e9e en puissance dans les refrains\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est une chanson qui d\u00e9crit les interrogations et les affres g\u00e9n\u00e9r\u00e9s en nous par les d\u00e9parts \u2013 pour fuir quoi, pour trouver quoi, pour rejoindre qui, pour quoi faire?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que cherche-t-on \u00e0 l&rsquo;horizon lorsqu&rsquo;on veut partir? A-t-on envie d&rsquo;\u00e9prouver un sentiment de libert\u00e9 (on se sent \u00ab\u00a0<em>le loup sans son collier \/ l&rsquo;arbre sans son espalier<\/em>\u00a0\u00bb )? Veut-on trouver ailleurs le repos et la paix (\u00ab\u00a0<em>Le dessin dans la forme d&rsquo;une maison<\/em>\u00a0\u00bb )? Esp\u00e8re-t-on que l\u00e0-bas au moins on aura des chances de \u00ab\u00a0<em>gu\u00e9rison<\/em>\u00ab\u00a0?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Avant l&rsquo;exil\u00a0\u00bb d\u00e9crit plus puissamment encore la sensation d&rsquo;arrachement qui nous assaille lorsqu&rsquo;on est sur le point de \u00ab\u00a0<em>tout quitter<\/em>\u00a0\u00bb : \u00ab\u00a0<em>on jette un dernier regard sur sa ville<\/em>\u00a0\u00bb et on pressent que quelque chose nous retient encore et donnera au d\u00e9part quelque chose de douloureux. La peur de l&rsquo;inconnu, dans tous les cas ou presque, et ce quand bien m\u00eame le d\u00e9part est ardemment attendu comme une d\u00e9livrance devant laquelle on a trop longtemps h\u00e9sit\u00e9. Quand on y a v\u00e9cu des moments heureux, on est aussi retenu par des lieux auxquels on est attach\u00e9 (\u00ab\u00a0<em>Le secret que personne ne sait, \/ c&rsquo;est qu&rsquo;on est n\u00e9 ici \/ et qu&rsquo;on sait ce qu&rsquo;on va laisser, \/ alors on reste assis<\/em>\u00a0\u00bb ), par des souvenirs\u2026 et par les personnes qui les peuplent, avec qui on a grandi, dont on est parfois issu (\u00ab\u00a0<em>Et l\u00e0-bas, sur le bord du quai, \/ comme la flamme d&rsquo;un briquet \/ dans une main qui tremble, \/ ce visage, on le conna\u00eet, \/ il nous ressemble<\/em>\u00a0\u00bb )\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quant au refrain, implacable et froid, il d\u00e9crit la sensation d&rsquo;isolement et l&rsquo;effroi qui peuvent nous envahir juste <em>apr\u00e8s<\/em> l&rsquo;exil: \u00ab\u00a0<em>Mais quand le sable a quitt\u00e9 le sablier, \/ que le marbre et la pierre se sont bris\u00e9s, \/ que le ch\u00eane a fini quand m\u00eame par retomber, \/ on se retrouve comme on est n\u00e9, \u00e0 nouveau dans un monde damn\u00e9 \/ sans rien ni personne pour nous aider<\/em>.\u00a0\u00bb Beaucoup de personnes sont si effray\u00e9es par la perspective du changement qu&rsquo;elles l&rsquo;imaginent sous cette forme mena\u00e7ante et qu&rsquo;elles pr\u00e9f\u00e8rent donc renoncer \u00e0 \u00ab\u00a0<em>tout quitter<\/em>\u00a0\u00bb : elles se r\u00e9solvent \u00e0 survivre dans leur pauvre quotidien, quitte \u00e0 passer \u00e0 c\u00f4t\u00e9 de magnifiques opportunit\u00e9s de voyages, d&rsquo;exp\u00e9riences et de rencontres \u2013 quitte \u00e0 mourir \u00e0 petit feu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malheureusement, il m&rsquo;est tr\u00e8s souvent arriv\u00e9 de m&rsquo;accrocher \u00e0 l&rsquo;\u00e9triqu\u00e9, et \u00e7a m&rsquo;arrive encore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est temps maintenant de laisser entrer l&rsquo;aventure dans ma vie, et advienne que pourra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0<em>Faire rouler dans ma main en pensant \u00e0 demain \/ quatre ch\u00e2taignes dans ma poche de manteau<\/em>\u00a0\u00bb . Quatre, plus deux qui font six.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Juste avant l&rsquo;exil,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">que cherche-t-il vers l&rsquo;horizon?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le dessin dans la forme d&rsquo;une maison,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ou peut-\u00eatre la gu\u00e9rison\u00a0\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"G\u00e9rard Manset - Avant l&#039;exil (1989)\" width=\"1230\" height=\"923\" src=\"https:\/\/www.youtube.com\/embed\/bdg0pgyfnqg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID1338\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"1338\"\n         id=\"da-reactions-slot-post-1338\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sortie en 1989 sur son quatorzi\u00e8me album \u00ab\u00a0Matrice\u00a0\u00bb , \u00ab\u00a0Avant l&rsquo;exil\u00a0\u00bb est l&rsquo;une de mes chansons pr\u00e9f\u00e9r\u00e9es de G\u00e9rard Manset, parce que la th\u00e9matique qu&rsquo;elle aborde (les s\u00e9parations) m&rsquo;a toujours&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2024\/01\/15\/gerard-manset-avant-lexil\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">G\u00e9rard Manset &#8211; \u00ab\u00a0Avant l&rsquo;exil\u00a0\u00bb<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID1338\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"1338\"\n         id=\"da-reactions-slot-post-1338\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":1339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[17,294],"class_list":["post-1338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musique","tag-chanson-francaise","tag-gerard-manset"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/1338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=1338"}],"version-history":[{"count":2,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/1338\/revisions"}],"predecessor-version":[{"id":6032,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/1338\/revisions\/6032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/1339"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=1338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=1338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=1338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}