{"id":14786,"date":"2026-02-22T13:12:53","date_gmt":"2026-02-22T12:12:53","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=14786"},"modified":"2026-02-24T22:01:55","modified_gmt":"2026-02-24T21:01:55","slug":"la-violence-de-lultradroite-et-le-spectre-de-la-guerre-civile","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2026\/02\/22\/la-violence-de-lultradroite-et-le-spectre-de-la-guerre-civile\/","title":{"rendered":"La violence de l&rsquo;ultradroite et le spectre de la guerre civile"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-9ac00cf961d1ea846fe5a532228b76c6 wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-e70f5eccd5679874f0e46a78358412fd wp-block-paragraph\">Depuis des ann\u00e9es, des groupuscules de militants \u00ab\u00a0identitaires\u00a0\u00bb, dont la plupart sont ouvertement racistes et dont beaucoup assument se r\u00e9f\u00e9rer au fascisme voire au nazisme, se livrent \u00e0 des attaques et des agressions contre des personnes racis\u00e9es et\/ou identifi\u00e9es comme des antifas, parfois m\u00eame contre des \u00e9lus (cf. le cas de Yannick Mevez, maire de Saint-Br\u00e9vin-les-Pins, qui soutenait un projet d&rsquo;extension d&rsquo;un centre d&rsquo;accueil de demandeurs d&rsquo;asile ouvert six ans plus t\u00f4t). Tout cela se d\u00e9roule dans une impunit\u00e9 quasi totale, sans susciter de r\u00e9probation ni de r\u00e9action \u00e0 la t\u00eate de l&rsquo;\u00c9tat ou au sein des principaux m\u00e9dias.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Violences-politiques-en-France.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"965\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Violences-politiques-en-France.jpg\" alt=\"\" class=\"wp-image-14790\" style=\"width:240px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Violences-politiques-en-France.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Violences-politiques-en-France-187x300.jpg 187w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Violences-politiques-en-France-385x620.jpg 385w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Violences-politiques-en-France-404x650.jpg 404w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Violences-politiques-en-France-280x450.jpg 280w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-b9aec00077872b31632b554e56a8302d wp-block-paragraph\">En France, la violence politique vient essentiellement de ce camp (cf. <a href=\"https:\/\/www.franceinfo.fr\/replay-radio\/le-vrai-du-faux\/vrai-ou-faux-mort-de-quentin-deranque-la-violence-d-extreme-droite-est-elle-vraiment-derisoire-par-rapport-a-la-violence-d-extreme-gauche_7787606.html\">cet article de France Info<\/a> qui fait tr\u00e8s bien le point sur le sujet). Selon Isabelle Sommier, professeure de sociologie politique \u00e0 l\u2019universit\u00e9 Paris-I, sp\u00e9cialiste des mouvements sociaux et de la violence politique, aitrice avec Fran\u00e7ois Audugier et Xavier Crettiez d&rsquo;un livre sur les <a href=\"https:\/\/www.pressesdesciencespo.fr\/fr\/book\/?gcoi=27246100505640\" data-type=\"link\" data-id=\"https:\/\/www.pressesdesciencespo.fr\/fr\/book\/?gcoi=27246100505640\">violences politiques en France<\/a>, \u00ab\u00a0<em>six meurtres peuvent \u00eatre imput\u00e9s \u00e0 l&rsquo;extr\u00eame-droite depuis 2022&nbsp;: ceux de Federico Martin Aramburu, des trois militants kurdes, d&rsquo;\u00c9ric Casado-Lopez et d&rsquo;Hichem Miraoui. En comparaison, l&rsquo;ultragauche n&rsquo;est soup\u00e7onn\u00e9e que d&rsquo;une seule mort ces quatre derni\u00e8res ann\u00e9es, celle de Quentin Deranque.<\/em>\u00a0\u00bb En prenant un peu de recul historique, \u00ab\u00a0<em>il y a eu 57 morts li\u00e9es \u00e0 des violences entre groupes politiques de 1986 \u00e0 2017 \u2013 52 du fait de la droite radicale et cinq du fait de la gauche radicale<\/em>\u00a0\u00bb (Isabelle Sommier toujours, dans une interview au&nbsp;journal <em>Le Monde<\/em>). En additionnant les six morts recens\u00e9es depuis 2022, le constat est sans appel&nbsp;: depuis 1986, l&rsquo;ultragauche a tu\u00e9 6 personnes, alors que l&rsquo;ultradroite en a tu\u00e9 58. Bref, l&rsquo;extr\u00eame droite a tu\u00e9 dix fois plus que l&rsquo;extr\u00eame gauche ces 40 derni\u00e8res ann\u00e9es&nbsp;!<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-be344ff8e6b9b5ed21043e1ea692ebd3 wp-block-paragraph\">Les violences \u00e9manant de l&rsquo;ultra-droite sont \u00e9galement majoritaires quand on \u00e9tudie les attaques qui n&rsquo;ont fait \u00ab\u00a0que\u00a0\u00bb des bless\u00e9s.&nbsp;Selon Isabelle Sommier, \u00ab\u00a0<em>Les agressions politiques sont pour plus de 60% le fait de la droite radicale et ont connu une progression consid\u00e9rable en moins de dix ans.<\/em>\u00a0\u00bb <\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-16b7064105a98759fb9360e3e6cb3c18 wp-block-paragraph\">Les donn\u00e9es sont claires aussi du c\u00f4t\u00e9 des attentats terroristes. En 2023, G\u00e9rald Darmanin, alors ministre de l&rsquo;Int\u00e9rieur, expliquait \u00e0&nbsp;Ouest-France&nbsp;que \u00ab\u00a0<em>dix projets<\/em>\u00a0\u00bb&nbsp;d&rsquo;attentats de l&rsquo;ultradroite avaient \u00e9t\u00e9&nbsp;\u00ab\u00a0<em>d\u00e9jou\u00e9s<\/em>\u00a0\u00bb&nbsp;ces derni\u00e8res ann\u00e9es. Dans la m\u00eame p\u00e9riode, l&rsquo;ultragauche n&rsquo;a commis aucun attentat et un seul attentat d\u00e9jou\u00e9 peut lui \u00eatre imput\u00e9, selon les donn\u00e9es du minist\u00e8re de l&rsquo;Int\u00e9rieur.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-24a1ec4eacd9eca1537b7bc5bb286b83 wp-block-paragraph\">M\u00eame chose ou presque au niveau europ\u00e9en&nbsp;: \u00ab\u00a0<em>Dans son dernier rapport sur l&rsquo;\u00e9tat de la menace terroriste en Europe portant sur l&rsquo;ann\u00e9e 2024 et qui s&rsquo;appuie sur des informations envoy\u00e9es par les pays membres, Europol ne rapporte aucune interpellation de membres de l&rsquo;ultragauche pour des motifs terroristes les trois derni\u00e8res ann\u00e9es observ\u00e9es. Onze avaient \u00e9t\u00e9 recens\u00e9es en 2020 et 3 en 2021. Au contraire, 69 membres de l&rsquo;ultradroite ont \u00e9t\u00e9 interpell\u00e9s dans le cadre d&rsquo;enqu\u00eates antiterroristes sur la m\u00eame p\u00e9riode, entre 2019 et 2024.<\/em>\u00a0\u00bb <\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1c847153e3e858f91101d6c9c499dd32 wp-block-paragraph\">Il faut enfin souligner que sauf exception, les violences issues de l&rsquo;ultra-gauche ne sont pas de m\u00eame nature que celles perp\u00e9tr\u00e9es par l&rsquo;ultra-droite. \u00ab\u00a0<em>L&rsquo;ultradroite s&rsquo;en prend principalement aux personnes, aux immigr\u00e9s, aux militants de gauche, faisant des morts et des bless\u00e9s, alors que l&rsquo;ultragauche, elle, s&rsquo;en prend principalement aux biens mat\u00e9riels, notamment pendant des manifestations.<\/em>\u00a0\u00bb Selon le CRGN (Centre de Recherche de la Gendarmerie Nationale), \u00ab\u00a0<em>la mouvance d&rsquo;ultragauche a maintenu son activit\u00e9 en France et revendiqu\u00e9 120 actions en 2025<\/em>\u00ab\u00a0, mais \u00ab\u00a0<em>la majorit\u00e9 de ces actions prennent pour cibles des b\u00e2timents ou des infrastructures : ceux li\u00e9s \u00e0 l&rsquo;environnement, au monde politique, ainsi que les commerces ont \u00e9t\u00e9 particuli\u00e8rement vis\u00e9s par des incendies volontaires et des d\u00e9gradations, suivis de pr\u00e8s par le r\u00e9seau \u00e9lectrique, les transports publics et le BTP<\/em>\u00a0\u00bb . Parmi les \u00ab\u00a0<em>actions majeures<\/em>\u00a0\u00bb&nbsp;de l&rsquo;ultragauche en 2025, on peut par exemple citer le sabotage du r\u00e9seau \u00e9lectrique pendant le Festival de Cannes, qui a provoqu\u00e9 une coupure de courant dans 160.000 foyers. Jusqu&rsquo;\u00e0 pr\u00e9sent en tous cas, lorsque l&rsquo;ultragauche met en \u0153uvre la violence physique, c&rsquo;est toujours pour cibler l&rsquo;ultra-droite. Celle-ci, en revanche, s&rsquo;attaque aussi et surtout \u00e0 des personnes, le plus souvent totalement innocentes et m\u00eame pas politis\u00e9es.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1fa54953bc44153c5f8e06b6a8526d10 wp-block-paragraph\">Malgr\u00e9 toutes ces donn\u00e9es, il a suffi d&rsquo;un seul mort, au cours d&rsquo;une rixe qui a semble-t-il \u00e9t\u00e9 provoqu\u00e9e par des militants d&rsquo;extr\u00eame-droite eux-m\u00eames, pour qu&rsquo;on assiste au d\u00e9ferlement <em>ad nauseam<\/em> de contre-v\u00e9rit\u00e9s que l&rsquo;on subit depuis une semaine&nbsp;: Quentin Deranque \u00e9tait un amoureux de la patrie respectueux et bien propre sur lui (alors qu&rsquo;on sait qu&rsquo;il a particip\u00e9 \u00e0 des manifestations fascistes au cours desquelles de nombreux saluts nazis ont \u00e9t\u00e9 lanc\u00e9s), l&rsquo;extr\u00eame-gauche tue, LFI est plus dangereuse que le RN,&nbsp;\u00ab\u00a0<em>Plus jamais un&nbsp;d\u00e9put\u00e9 LFI&nbsp;\u00e0 l&rsquo;Assembl\u00e9e nationale<\/em>\u00a0\u00bb , etc.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-68ca5e7c99bb13b904b70769176aaaf7 wp-block-paragraph\">Le bouquet a \u00e9t\u00e9 la minute de silence \u00e0 l&rsquo;Assembl\u00e9e Nationale et le d\u00e9ploiement d&rsquo;une banderole \u00e0 l&rsquo;effigie de Quentin Deranque sur la fa\u00e7ade du si\u00e8ge de la r\u00e9gion Rh\u00f4ne-Alpes Auvergne. Un jeune faf mis \u00e0 l&rsquo;honneur dans la ville de Jean Moulin \ud83e\udd2e Et pourquoi pas la l\u00e9gion d&rsquo;honneur \u00e0 titre posthume, tant qu&rsquo;on y est? Comme l&rsquo;a bien dit un commentateur sur Fessebouque que je ne connais pas (Patrick Barbier), tout \u00e7a fait penser \u00e0 la fa\u00e7on dont Palpatine obtient les pleins pouvoirs du S\u00e9nat de Star Wars, en faisant croire qu&rsquo;il va les utiliser pour r\u00e9tablir la paix dans la galaxie, alors que c&rsquo;est justement cette reddition des d\u00e9mocrates qui va lui permettre d&rsquo;installer un Empire totalitaire. Chez nous aussi, la mansu\u00e9tude de l&rsquo;Etat, de la macronie et de la droite dite \u00ab\u00a0parlementaire\u00a0\u00bb \u00e0 l&rsquo;\u00e9gard de l&rsquo;ultra-droite commence \u00e0 puer tr\u00e8s, tr\u00e8s fort.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Menaces-Salome-Saque.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"503\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Menaces-Salome-Saque.jpg\" alt=\"\" class=\"wp-image-14791\" style=\"width:315px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Menaces-Salome-Saque.jpg 400w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Menaces-Salome-Saque-239x300.jpg 239w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Menaces-Salome-Saque-358x450.jpg 358w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-522272b00ccaefa47eebdf92ca5076c0 wp-block-paragraph\">Cela fait des ann\u00e9es que j&rsquo;observe la polarisation de la soci\u00e9t\u00e9 fran\u00e7aise s&rsquo;accentuer et devenir de plus en plus violente, et pas que sur le sujet de l&rsquo;immigration et de \u00ab\u00a0l&rsquo;identit\u00e9 nationale\u00a0\u00bb (on constate \u00e0 peu pr\u00e8s la m\u00eame chose avec la mont\u00e9e du masculinisme ou de l&rsquo;ecolo-bashing, par exemple). Il suffit de fr\u00e9quenter un peu les r\u00e9seaux sociaux pour savoir que la haine contre les arabes, les femmes, les homos (notamment les lesbiennes), les \u00ab\u00a0gauchiasses\u00a0\u00bb ou les \u00ab\u00a0socialopes\u00a0\u00bb, cette haine multiforme et aussi cr\u00e9tine que m\u00e9chante (voir ci-contre l&rsquo;exemple de ce que Salom\u00e9 Saqu\u00e9 re\u00e7oit sous ses publications), s&rsquo;exprime de fa\u00e7on de plus en plus d\u00e9complex\u00e9e, avec des mots de plus en plus obsc\u00e8nes et des menaces de plus en plus pr\u00e9cises.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-525f713efac22b7ec17b60189cca4592 wp-block-paragraph\">Pour \u00eatre honn\u00eate, la haine peut aussi s&rsquo;observer de l&rsquo;autre c\u00f4t\u00e9&nbsp;: il y a aussi sur le sol fran\u00e7ais des gens qui pensent que l&rsquo;Occident est un Satan qu&rsquo;il faut \u00e9radiquer, qui suivent des pr\u00eaches salafistes appelant \u00e0 faire de la France une r\u00e9publique islamique\u2026 Ces gens ne me font pas moins peur \u2013 d&rsquo;ailleurs il y en a qui n&rsquo;h\u00e9sitent pas \u00e0 agir conform\u00e9ment \u00e0 leurs convictions, et on a vu l&rsquo;enfer qu&rsquo;ils sont capable de d\u00e9clencher, \u00e0 <em>Charlie-Hebdo<\/em>, au Bataclan ou sur la promenade des Anglais\u2026<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8c62955f5c5a88f831383e688fb8d935 wp-block-paragraph\">Quand je pense \u00e0 l&rsquo;avenir, je suis d&rsquo;autant plus inquiet que nous sommes encore dans une soci\u00e9t\u00e9 qui reste \u00e0 peu pr\u00e8s stable, bien qu&rsquo;elle se d\u00e9sagr\u00e8ge de tous c\u00f4t\u00e9s. Que deviendra la soci\u00e9t\u00e9 fran\u00e7aise dans un contexte d&rsquo;effondrement \u00e9conomique et social, lorsque l&rsquo;\u00c9tat et le syst\u00e8me de protection sociale surendett\u00e9s tailleront plus encore dans les services publics ou l&rsquo;aide sociale, lorsque le syst\u00e8me de retraites explosera carr\u00e9ment, lorsque les manifestations de la crise \u00e9cologique seront de plus en plus co\u00fbteuses et ing\u00e9rables, lorsque l&rsquo;approvisionnement en eau, en nourriture, en \u00e9nergie, en sant\u00e9 ou en s\u00e9curit\u00e9 publique ne sera plus du tout garanti \u00e0 tout le monde par des services encadr\u00e9s par la loi (c&rsquo;est la d\u00e9finition de l&rsquo;effondrement que propose Yves Cochet)&nbsp;? Qu&rsquo;arrivera-t-il lorsque beaucoup plus de gens auront beaucoup plus de raisons d&rsquo;\u00eatre beaucoup plus en col\u00e8re, lorsque beaucoup plus de gens auront envie de se rassurer en d\u00e9signant des boucs \u00e9missaires et en s&rsquo;en remettant \u00e0 un \u00ab\u00a0homme fort\u00a0\u00bb capable de \u00ab\u00a0nettoyer les \u00e9curies d&rsquo;Augias et de remettre de l&rsquo;ordre dans ce bordel\u00a0\u00bb&nbsp;? Qu&rsquo;arrivera-t-il alors, dans une soci\u00e9t\u00e9 o\u00f9, qui plus est, le sens de la nuance, la recherche du dialogue et du compromis et l&rsquo;honn\u00eatet\u00e9 intellectuelle sont de plus en plus lamin\u00e9s par l&rsquo;enfermement dans des bulles informationnelles sur les r\u00e9seaux sociaux&nbsp;? Dans une soci\u00e9t\u00e9 o\u00f9 l&rsquo;IA permet d\u00e9j\u00e0 de produire des fake news quasiment ind\u00e9tectables, ce qui permet encore plus facilement de raconter n&rsquo;importe quoi pour attiser la col\u00e8re et la haine&nbsp;?<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-562495297dce228bd7222b5929efca40 wp-block-paragraph\">Plus le temps passe, plus j&rsquo;ai l&rsquo;impression que les soci\u00e9t\u00e9 fran\u00e7aise (comme d&rsquo;autres) est une poudri\u00e8re, plus j&rsquo;ai du mal \u00e0 voir comment \u00e7a pourrait finir autrement que par des affrontements violents, voire une guerre civile (dans le contexte actuel, que se passerait-il par exemple si un attentat islamiste faisait un carnage dans une \u00e9glise, une \u00e9cole ou un EHPAD&nbsp;?).<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color has-link-color wp-elements-c5995833d97d0e9c85ea96ca8bd01cb2 wp-block-paragraph\">\/\/\/\/\/\/<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-f5388b4a8094d51c61591ba747225006 wp-block-paragraph\">En pensant \u00e0 tout cela ces jours-ci, il m&rsquo;est revenu en m\u00e9moire cette BD de Pierre Christin et Enki Bilal, \u00ab\u00a0Les phalanges de l&rsquo;ordre noir\u00a0\u00bb. En voici le pitch&nbsp;(toute ressemblance avec ce qui est peut-\u00eatre en train de se mettre en place n&rsquo;est peut-\u00eatre pas fortuite)&nbsp;:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Les-phalanges-de-lordre-noir-interieur.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Les-phalanges-de-lordre-noir-interieur.jpg\" alt=\"\" class=\"wp-image-14787\" style=\"width:524px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Les-phalanges-de-lordre-noir-interieur.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Les-phalanges-de-lordre-noir-interieur-225x300.jpg 225w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Les-phalanges-de-lordre-noir-interieur-465x620.jpg 465w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Les-phalanges-de-lordre-noir-interieur-488x650.jpg 488w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Les-phalanges-de-lordre-noir-interieur-338x450.jpg 338w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1bcaff01c86db1eff2c3cbf2ae49a2b6 wp-block-paragraph\">\u00ab\u00a0<em>Par une nuit d&rsquo;hiver en Espagne, sur les hauts plateaux de la province de l&rsquo;Aragon, une exp\u00e9dition punitive s&rsquo;abat sur le petit village de Nieves. Tous ses habitants, y compris les femmes et les enfants, sont ex\u00e9cut\u00e9s et le village est incendi\u00e9. L&rsquo;attentat est revendiqu\u00e9 par un groupe politique, les Phalanges de l&rsquo;Ordre Noir, au nom des <\/em><em>\u00ab<\/em><em>valeurs de l&rsquo;Occident chr\u00e9tien&nbsp;<\/em><em>\u00bb<\/em><em>. Le village, haut lieu des affrontements entre r\u00e9publicains et franquistes \u00e0 la fin des ann\u00e9es trente lors de la guerre d&rsquo;Espagne, venait de voter massivement \u00e0 gauche lors des derni\u00e8res \u00e9lections\u2026 Convaincus que ce massacre signe le retour de l&rsquo;extr\u00eame droite qu&rsquo;ils ont autrefois combattue, un groupe d&rsquo;anciens des brigades internationales, quarante ans apr\u00e8s, se d\u00e9cide \u00e0 reprendre les armes. De l&rsquo;Espagne \u00e0 Suisse en passant par l&rsquo;Italie, les Pays-Bas et la France, une dizaine d&rsquo;hommes que l&rsquo;\u00e2ge a rendus las, mais toujours fid\u00e8les \u00e0 leurs convictions de jeunesse, vont ainsi donner la chasse \u00e0 leurs vieux ennemis, jusqu&rsquo;\u00e0 l&rsquo;affrontement final.<\/em>\u00a0\u00bb <\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-6a17218c07fa620654ec51e476ee4998 wp-block-paragraph\">Manifestement, de plus en plus de gens, en France, se pr\u00e9parent \u00e0 cet affrontement, et m\u00eame le souhaitent ardemment (\u00ab\u00a0Viva la muerte!\u00a0\u00bb). Tr\u00e8s souvent, ces gens ne sont pas des vieux combattants fatigu\u00e9s mais des jeunes fascin\u00e9s par la violence et qui n&rsquo;en ont pas peur. Et malheureusement, je crains qu&rsquo;ils soient en train de gagner.<\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID14786\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"14786\"\n         id=\"da-reactions-slot-post-14786\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Depuis des ann\u00e9es, des groupuscules de militants \u00ab\u00a0identitaires\u00a0\u00bb, dont la plupart sont ouvertement racistes et dont beaucoup assument se r\u00e9f\u00e9rer au fascisme voire au nazisme, se livrent \u00e0 des attaques&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2026\/02\/22\/la-violence-de-lultradroite-et-le-spectre-de-la-guerre-civile\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">La violence de l&rsquo;ultradroite et le spectre de la guerre civile<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID14786\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"14786\"\n         id=\"da-reactions-slot-post-14786\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":14789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[97,674,738],"class_list":["post-14786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","tag-effondrement-collapse","tag-extreme-droite","tag-politique"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/14786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=14786"}],"version-history":[{"count":16,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/14786\/revisions"}],"predecessor-version":[{"id":14857,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/14786\/revisions\/14857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/14789"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=14786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=14786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=14786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}