{"id":14858,"date":"2026-02-25T08:58:30","date_gmt":"2026-02-25T07:58:30","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=14858"},"modified":"2026-02-25T23:50:05","modified_gmt":"2026-02-25T22:50:05","slug":"louis-chedid-anne-ma-soeur-anne","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2026\/02\/25\/louis-chedid-anne-ma-soeur-anne\/","title":{"rendered":"Louis Chedid &#8211; \u00ab\u00a0Anne ma s\u0153ur Anne\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d939bdeb6b1a4b9a244daa61875db127 wp-block-paragraph\">Quelques jours apr\u00e8s la marche lyonnaise en hommage \u00e0 Quentin Deranque (qui en fait \u00e9tait, comme pr\u00e9vu, une d\u00e9monstration de force des factions d&rsquo;ultra-droite), j&rsquo;ai pens\u00e9 \u00e0 cette chanson en me disant qu&rsquo;elle d\u00e9crit bien les sueurs froides qui, ces temps-ci, prennent les gens attach\u00e9s \u00e0 la d\u00e9mocratie et \u00e0 l&rsquo;\u00e9galit\u00e9 entre les \u00eatre humains.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3285a57ffb5235a430248a7b1730e8c7 wp-block-paragraph\">Louis Chedid a sorti cette chanson en 1985, un an apr\u00e8s des \u00e9lections europ\u00e9ennes qui avaient vu le FN obtenir pour la premi\u00e8re fois des si\u00e8ges (dix) au Parlement Europ\u00e9en. \u00c0 l&rsquo;\u00e9poque, le leader du parti d&rsquo;<a href=\"https:\/\/gregoryderville.com\/index.php\/tag\/extreme-droite\/\" data-type=\"link\" data-id=\"https:\/\/gregoryderville.com\/index.php\/tag\/extreme-droite\/\">extr\u00eame-droite<\/a> n&rsquo;\u00e9tait pas un jeune homme propre sur lui, adepte de la salle et des r\u00e9seaux sociaux et au discours faussement polic\u00e9, mais un vieux m\u00e2le vicieux qui, selon son humeur, pr\u00e9tendait que les chambres \u00e0 gaz \u00e9taient \u00ab\u00a0<em>un d\u00e9tail de l&rsquo;histoire<\/em>\u00a0\u00bb ou faisait \u00e0 leur propos des jeux de mots d\u00e9go\u00fbtants (\u00ab\u00a0<em>Durafour cr\u00e9matoire<\/em>\u00a0\u00bb ), quand il n&rsquo;\u00e9tait pas occup\u00e9 \u00e0 vomir sur ceux qu&rsquo;il appelait les \u00ab\u00a0<em>sida\u00efques<\/em>\u00a0\u00bb . Il y avait de quoi flipper, en effet, alors Louis Chedid \u00e9crivit et composa \u00ab\u00a0Anne ma s\u0153ur Anne\u00a0\u00bb, pour exorciser sa peur. Dans une interview en 2022, il explique ainsi l&rsquo;importance que cette chanson a toujours eu pour lui&nbsp;:<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-99758419c05d56b1c7bd8ccfcaa351f2 wp-block-paragraph\">\u00ab\u00a0<em>Quand j&rsquo;\u00e9tais petit, on nous a montr\u00e9 \u00e0 l&rsquo;\u00e9cole un film d&rsquo;Alain Resnais qui s&rsquo;appelait <\/em><em>\u00ab<\/em><em>&nbsp;Nuit et brouillard&nbsp;<\/em><em>\u00bb<\/em><em>&nbsp;(1955), qui parle justement des camps de concentration. Et mes parents comme les gens ne parlaient pas trop de toute cette p\u00e9riode de la Seconde guerre mondiale, des camps de concentration, de la Shoah et tout \u00e7a. Nous, on n&rsquo;est pas juifs, on est chr\u00e9tiens maronites et il y a beaucoup de gens qui pensent, gr\u00e2ce ou \u00e0 cause, je ne sais pas, de cette chanson qu&rsquo;on est juifs, mais ce n&rsquo;est pas le cas. Il ne faut pas \u00eatre noir pour d\u00e9tester l&rsquo;esclavage. On est des \u00eatres humains et les uns et les autres, on a le droit de d\u00e9noncer des choses. On n&rsquo;est pas oblig\u00e9 d&rsquo;\u00eatre de certaines confessions pour d\u00e9noncer.&nbsp;Et donc, quand j&rsquo;\u00e9tais petit, il y avait l&rsquo;extr\u00eame-droite et c&rsquo;\u00e9tait 0,2% de la population qui votait aux \u00e9lections pour elle. Les fachos rasaient les murs. Ils se cachaient. Et puis tout d&rsquo;un coup tac, on voit le truc revivre. Et je n&rsquo;en revenais pas. Je me disais ce n&rsquo;est pas possible. Et puis malheureusement, cette chanson est encore plus d&rsquo;actualit\u00e9 aujourd&rsquo;hui, d&rsquo;o\u00f9 sa long\u00e9vit\u00e9. Je dis souvent que j&rsquo;aurais pr\u00e9f\u00e9r\u00e9 qu&rsquo;elle soit obsol\u00e8te, de me dire : je ne la chante plus, il n&rsquo;y en a plus besoin\u2026<\/em>\u00ab\u00a0<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"453\" height=\"706\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Anne-Frank.jpg\" alt=\"\" class=\"wp-image-14863\" style=\"width:324px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Anne-Frank.jpg 453w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Anne-Frank-192x300.jpg 192w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Anne-Frank-398x620.jpg 398w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Anne-Frank-417x650.jpg 417w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Anne-Frank-289x450.jpg 289w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-86fe4478d16a802d3e1ae16938e8e3a0 wp-block-paragraph\">La chanson fait bien s\u00fbr une double r\u00e9f\u00e9rence au conte de Charles Perrault \u00ab\u00a0La Barbe bleue\u00a0\u00bb (\u00ab\u00a0<em>Anne, ma soeur Anne, ne vois-tu rien venir<\/em>&nbsp;<em>?<\/em>\u00a0\u00bb ) et au <em>Journal <\/em>d&rsquo;Anne Frank. S&rsquo;adressant \u00e0 la jeune juive n\u00e9erlandaise morte dans le camp de Bergen-Belsen en 1945, Louis Chedid dit qu&rsquo;il aimerait pouvoir la rassurer sur le fait qu&rsquo;on n&rsquo;a pas oubli\u00e9 l&rsquo;horreur nazie (\u00ab\u00a0<em>J&rsquo;aurais tant voulu te dire, p&rsquo;tite fille martyre \/ \u00abAnne, ma s\u0153ur Anne \/ Tu peux dormir tranquille, elle reviendra plus \/ La vermine !&nbsp;\u00bb<\/em>\u00a0\u00bb , mais il constate avec effroi que \u00ab\u00a0<em>cette nazi-nostalgie (\u2026) ressort de sa tani\u00e8re<\/em>\u00a0\u00bb , avec \u00ab\u00a0<em>Les m\u00eames discours, \/ les m\u00eames slogans, \/ les m\u00eames aboiements<\/em>\u00a0\u00bb , avec les m\u00eames symboles (\u00ab\u00a0<em>Croix gamm\u00e9e, bottes \u00e0 clous, et toute la panoplie<\/em>\u00a0\u00bb ). Pire encore, chante-t-il, cette nazi-nostalgie \u00ab\u00a0<em>a pignon sur rue, des adeptes, un parti<\/em>\u00a0\u00bb \u2026 Et selon Chedid, la faute en incombait notamment \u00e0 celles et ceux qui, face \u00e0 ce retour de \u00ab\u00a0<em>l&rsquo;historique hyst\u00e9rie<\/em>\u00a0\u00bb , manifestaient \u00ab\u00a0<em>beaucoup d&rsquo;indiff\u00e9rence, de patience malvenue\u00a0\u00bb (\u2026) beaucoup trop d&rsquo;indulgence, trop de bonnes mani\u00e8res<\/em>\u00a0\u00bb .<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-b493cb72d0ebb5d268c29a6c8e0f855e wp-block-paragraph\">J&rsquo;avoue que lorsque j&rsquo;entendais cette chanson dans les ann\u00e9es 90-2000, elle me semblait assez symptomatique d&rsquo;une gauche qui jouait \u00e0 se faire peur en se r\u00e9p\u00e9tant la c\u00e9l\u00e8bre phrase de Bertolt Brecht (\u00ab\u00a0<em>Il est encore f\u00e9cond le ventre d\u2019o\u00f9 surgit la b\u00eate immonde<\/em>\u00a0\u00bb ), et qui se voilait la face sur ses propres responsabilit\u00e9s dans la mont\u00e9e du FN. Pour \u00eatre honn\u00eate, je continue \u00e0 penser que depuis quarante ans on a trop facilement trait\u00e9 de fachos les \u00e9lecteurs et les \u00e9lectrices de ce parti (m\u00eame si bien s\u00fbr il y en a qui le sont), contribuant ainsi \u00e0 les radicaliser, au lieu de s&rsquo;attaquer \u00e0 la racine des raisons pour lesquelles ils se laissent s\u00e9duire par le discours frontiste.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-072f883591e274604324da9ac54b5746 wp-block-paragraph\">Mais depuis quelques ann\u00e9es, les choses ont chang\u00e9. Le RN est d\u00e9sormais le premier parti de France, et je vois mal comment on pourrait \u00e9viter son accession au pouvoir avec ses alli\u00e9s zemmouriens ou ciottistes (sachant que les Wauquiez, Darmanin ou Reta\u00efaut sont pr\u00eats \u00e0 les rejoindre).<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5742de15d2b8711e8c5af885d832c40a wp-block-paragraph\">Bien s\u00fbr, on n&rsquo;est pas encore gouvern\u00e9s par un r\u00e9gime fasciste (ceux qui pr\u00e9tendent cela sont \u00e0 mon avis \u00e0 c\u00f4t\u00e9 de la plaque et contribuent en fait \u00e0 banaliser et \u00e0 normaliser le fascisme). Bien s\u00fbr la politique de l&rsquo;\u00c9tat fran\u00e7ais est \u00e0 bien des \u00e9gards de plus en plus naus\u00e9abonde, mais enfin il n&rsquo;y a pas encore en France une milice gestapiste ou une ICE trumpiste.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-c9949f88f0470b4b20099da2bac2feb5 wp-block-paragraph\">Certes, il y a encore un peu de marge.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-a39d3d2e9ea238f0fcada648f5d4ea8d wp-block-paragraph\">Mais il y en a de moins en moins\u2026<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Manifestation-ultradroite-salut-nazi.jpg\" alt=\"\" class=\"wp-image-14868\" style=\"width:444px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Manifestation-ultradroite-salut-nazi.jpg 800w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Manifestation-ultradroite-salut-nazi-300x200.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Manifestation-ultradroite-salut-nazi-768x512.jpg 768w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Manifestation-ultradroite-salut-nazi-600x400.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/02\/Manifestation-ultradroite-salut-nazi-400x267.jpg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-13e2339d0dab8639f6f82ace9b868fc5 wp-block-paragraph\">D&rsquo;abord parce que l&rsquo;ultradroite s&rsquo;enhardit et se sent de plus en plus autoris\u00e9e \u00e0 afficher publiquement sa haine et son d\u00e9sir de violence (\u00ab\u00a0Viva la muerte&nbsp;!\u00a0\u00bb est l&rsquo;un de ses slogans), et pas que sur les r\u00e9seaux sociaux. Quand je vois les jeunes aux cheveux courts et aux tenues et aux lunettes noires faire des saluts nazis en pleine rue sous couvert de \u00ab\u00a0patriotisme\u00a0\u00bb et de \u00ab\u00a0d\u00e9fense des valeurs chr\u00e9tiennes\u00a0\u00bb, je me dis que ceux-l\u00e0 sont impatients de pouvoir tranquillement chasser et bastonner les militant\u00b7es antiracistes et tout ce qui ressemble de pr\u00e8s ou de loin \u00e0 un\u00b7e personne racis\u00e9\u00b7e ou homosexuelle ou \u00e0 un\u00b7e \u00e9colo\u2026 Pour ces jeunes droitard\u00e9s, racistes, masculinistes et homophobes, la ratonnade a l&rsquo;air d&rsquo;\u00eatre le loisir le plus excitant.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-00736b6552d3b452208c844dd9cd7044 wp-block-paragraph\">Mais ce que je trouve le pire, en fait, c&rsquo;est qu&rsquo;ils puissent faire tout cela sous le regard passif des forces de l&rsquo;ordre et que la Justice ne les poursuive pas pour leurs agissements. Ce que je trouve le pire, c&rsquo;est que du c\u00f4t\u00e9 de la droite dite \u00ab\u00a0parlementaire\u00a0\u00bb, on est d\u00e9j\u00e0 bien au-del\u00e0 de l&rsquo;indulgence coupable et de la complaisance vis-\u00e0-vis de l&rsquo;extr\u00eame-droite. Depuis des ann\u00e9es, LR et la Macronie surfent sur la vague raciste dans l&rsquo;espoir de r\u00e9cup\u00e9rer une petite partie de l&rsquo;\u00e9lectorat du RN (ou de gouverner avec lui). Maintenant ils en sont \u00e0 mettre un signe \u00e9gal entre la gauche (accus\u00e9e d&rsquo;\u00eatre antis\u00e9mite et anti-r\u00e9publicaine, et dont on r\u00e9clame qu&rsquo;elle soit isol\u00e9e par un \u00ab\u00a0<em>cordon sanitaire<\/em>\u00a0\u00bb ) et l&rsquo;extr\u00eame-droite (qui serait d\u00e9sormais \u00ab\u00a0<em>dans l&rsquo;arc r\u00e9publicain<\/em>\u00a0\u00bb ). Et lorsqu&rsquo;un jeune faf est lynch\u00e9 dans cette capitale de l&rsquo;ultra-droite fran\u00e7aise qu&rsquo;est Lyon (ce qui est scandaleux et injustifiable, bien entendu), \u00e0 la suite d&rsquo;une rixe que ses amis avaient eux-m\u00eames provoqu\u00e9e, on lui rend hommage par une minute de silence \u00e0 l&rsquo;Assembl\u00e9e Nationale, on ment effront\u00e9ment en pr\u00e9tendant que \u00ab\u00a0<em>LFI tue<\/em>\u00a0\u00bb alors que 90% des assassinats politiques sont commis par des militants de l&rsquo;ultra-droite, on demande que le portrait de ce jeune homme soit affich\u00e9 sur le fronton de la mairie de la ville de Jean Moulin (Jean-Michel Hole-Ass s&rsquo;est d\u00e9finitivement d\u00e9shonor\u00e9), on laisse des factions fascistes se r\u00e9unir et d\u00e9filer dans les rues de Lyon, on qualifie de \u00ab\u00a0sans histoire\u00a0\u00bb un rassemblement dans lequel des saluts nazis et des insultes racistes et homophobes ont \u00e9t\u00e9 lanc\u00e9s\u2026<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d35c3715e07344099fc714110587d2b9 wp-block-paragraph\">Parmi les choses qui m&rsquo;alarment, il y a aussi le fait que des milliardaires du type Bollor\u00e9 ou St\u00e9rin mettent leur fortune au service de l&rsquo;extr\u00eame-droite en achetant \u00e0 tour de bras des m\u00e9dias pour diffuser leur id\u00e9ologie rance et pour disqualifier la gauche et l&rsquo;anti-racisme, mais aussi l&rsquo;\u00e9cologie ou le f\u00e9minisme. Quand il m&rsquo;arrive de tomber sur un extrait de C-News, d&rsquo;Europe1, du <em>JDD<\/em>, de <em>Valeurs actuelles<\/em> ou m\u00eame du <em>Figaro<\/em>, je pense souvent \u00e0 la fameuse formule de Pierre Desproges disant que quand on lit <em>Minute<\/em>, on a \u00ab\u00a0<em>\u00e0 la fois La naus\u00e9e et Les mains sales<\/em>\u00a0\u00bb .<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-25f8a86b7b52aec0948a48f7a5e7801b wp-block-paragraph\">En 1985, Louis Chedid, qui \u00e9tait jusqu&rsquo;alors connu pour des chansons plut\u00f4t tranquilles, l\u00e9g\u00e8res et m\u00eame joyeuses (son premier succ\u00e8s \u00e9tait une chanson satirique, \u00ab\u00a0T&rsquo;a beau pas \u00eatre beau\u00a0\u00bb), a chang\u00e9 de ton. Aujourd&rsquo;hui je crois qu&rsquo;il est temps de s&rsquo;inqui\u00e9ter <em>vraiment<\/em>&nbsp;: le fascisme est aux portes du pouvoir, et il est facile d&rsquo;imaginer la brutalit\u00e9 avec laquelle il gouvernera lorsqu&rsquo;il s&rsquo;en emparera.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-03b02a8bd89ba4548f00106e3f77d4a4 wp-block-paragraph\">\u00ab\u00a0J\u2019arrive pas \u00e0 y croire,<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-75ef00f07db52f13269e81097b009fd9 wp-block-paragraph\">c\u2019est comme un cauchemar\u2026\u00a0\u00bb<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color has-link-color wp-elements-c5995833d97d0e9c85ea96ca8bd01cb2 wp-block-paragraph\">\/\/\/\/\/\/<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-e95a4c387613b09e0763f43191c57286 wp-block-paragraph\">Pour parler un peu de musique, quand m\u00eame\u2026 Dans la version originale, celle qui est sortie comme premier single de l&rsquo;album \u00ab\u00a0Anne ma s\u0153ur\u00a0\u00bb en 1985, cette chanson a une sonorit\u00e9 jazzy et m\u00eame swing, son rythme ent\u00eatant est jou\u00e9 par un synth\u00e9 assez cheap (comme c&rsquo;\u00e9tait fr\u00e9quent \u00e0 l&rsquo;\u00e9poque), et la voix est feutr\u00e9e, comme si Louis Chedid avait voulu attendrir l&rsquo;oreille pour faire mieux passer le caract\u00e8re angoissant des paroles. En 2022, \u00ab\u00a0Anne ma s\u0153ur\u00a0\u00bb a \u00e9t\u00e9 r\u00e9enregistr\u00e9e en piano voix sur l&rsquo;album \u00ab\u00a0En noires et blanc\u00a0\u00bb, en collaboration avec le pianiste Yvan Cassar. Le tempo et la m\u00e9lodie restent les m\u00eames, mais le ton est plus grave, la voix plus lasse, et la chanson prend l&rsquo;allure d&rsquo;une comptine \u00e0 l&rsquo;inqui\u00e9tante \u00e9tranget\u00e9, dans laquelle quelque chose de sinistre est cach\u00e9 sous une jovialit\u00e9 factice. Personnellement je pr\u00e9f\u00e8re cette version, ce pourquoi je la place en premier ci-dessous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Anne ma s\u0153ur Anne (Version Piano \u2013 Voix)\" width=\"1230\" height=\"923\" src=\"https:\/\/www.youtube.com\/embed\/4qfrlYzP5X8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Anne, ma s\u0153ur Anne\" width=\"1230\" height=\"923\" src=\"https:\/\/www.youtube.com\/embed\/2jFkn4kjjiU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID14858\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"14858\"\n         id=\"da-reactions-slot-post-14858\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quelques jours apr\u00e8s la marche lyonnaise en hommage \u00e0 Quentin Deranque (qui en fait \u00e9tait, comme pr\u00e9vu, une d\u00e9monstration de force des factions d&rsquo;ultra-droite), j&rsquo;ai pens\u00e9 \u00e0 cette chanson en&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2026\/02\/25\/louis-chedid-anne-ma-soeur-anne\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">Louis Chedid &#8211; \u00ab\u00a0Anne ma s\u0153ur Anne\u00a0\u00bb<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID14858\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"14858\"\n         id=\"da-reactions-slot-post-14858\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":14859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,85],"tags":[17,674,855,738],"class_list":["post-14858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musique","category-politique","tag-chanson-francaise","tag-extreme-droite","tag-louis-chedid","tag-politique"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/14858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=14858"}],"version-history":[{"count":30,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/14858\/revisions"}],"predecessor-version":[{"id":14906,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/14858\/revisions\/14906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/14859"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=14858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=14858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=14858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}