{"id":15190,"date":"2026-03-27T19:47:59","date_gmt":"2026-03-27T18:47:59","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=15190"},"modified":"2026-03-28T09:02:00","modified_gmt":"2026-03-28T08:02:00","slug":"le-feminicide-est-le-produit-du-patriarcat","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2026\/03\/27\/le-feminicide-est-le-produit-du-patriarcat\/","title":{"rendered":"Le f\u00e9minicide est le produit du patriarcat"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-9ac00cf961d1ea846fe5a532228b76c6 wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-112ebf8f03dc517112bf0ad585782d1a wp-block-paragraph\">Deux de plus. Une fois de plus, le <a href=\"https:\/\/gregoryderville.com\/index.php\/tag\/feminisme-partriarcat\/\" data-type=\"link\" data-id=\"https:\/\/gregoryderville.com\/index.php\/tag\/feminisme-partriarcat\/\">patriarcat <\/a>a tu\u00e9 en France.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d9799c5e8b0b80d092b8a2ffc5ee2668 wp-block-paragraph\">En 2004, les forces de l&rsquo;ordre ont enregistr\u00e9 en France 107 victimes de f\u00e9minicides au sein du couple, 270 victimes de tentatives de f\u00e9minicide au sein du couple, 906 victimes de suicide ou de tentative de suicide suite au harc\u00e8lement par un conjoint ou par un ex-conjoint. Il y a quelques jours, Cedric Prizzon a rajout\u00e9 d&rsquo;un seul coup deux noms sur la liste.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1bd3cdcbd389207ae3500981dd963d83 wp-block-paragraph\">Une fois de plus, l&rsquo;assassin est un masculiniste av\u00e9r\u00e9, un homme violent et incapable de contr\u00f4ler ses impulsions, convaincu que \u00ab\u00a0sa\u00a0\u00bb femme lui appartient, convaincu aussi que la Justice et la soci\u00e9t\u00e9 toute enti\u00e8re complotaient contre lui pour le priver de \u00ab\u00a0son\u00a0\u00bb fils, alors que si la garde lui avait \u00e9t\u00e9 retir\u00e9e, c&rsquo;\u00e9tait tout simplement parce que c&rsquo;\u00e9tait un homme violent (d&rsquo;ailleurs il poss\u00e9dait ill\u00e9galement un fusil).<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-b50363b2c0542339e11071ce09c3954a wp-block-paragraph\">C\u00e9dric Prizzon \u00e9tait un membre actif du groupe Facebook \u00ab\u00a0Papas en col\u00e8re\u00a0\u00bb, et il diffusait r\u00e9guli\u00e8rement des discours publics dans lequel il adoptait une position victimaire (comme le font si souvent les hommes pervers et manipulateurs). Il accusait \u00e0 tout bout de champ son ex-compagne de mentir, il la qualifiait par exemple de&nbsp;\u00ab\u00a0<em>folle psychopathe, avec toute sa famille de psychopathes<\/em>\u00a0\u00bb . En mars&nbsp;2023, il avait manifest\u00e9 devant l&rsquo;h\u00f4tel de ville de Rodez en tenant un grand panneau blanc sur lequel il avait imprim\u00e9 en rouge \u00ab\u00a0<em>mon fils en grave danger<\/em>\u00a0\u00bb . Interrog\u00e9 ce jour-l\u00e0 par un journaliste de la presse locale, il proclamait que \u00ab\u00a0<em>en France, \u00eatre p\u00e8re est un crime<\/em>\u00a0\u00bb , il affirmait qu&rsquo;il voulait alerter sur la \u00ab\u00a0<em>grave erreur judiciaire<\/em>\u00a0\u00bb dont il s&rsquo;estimait la victime, et il affirmait sa d\u00e9termination&nbsp;: \u00ab\u00a0<em>J&rsquo;irai jusqu\u2019au bout, je manifeste tous les jours devant le tribunal de Rodez et, s&rsquo;il le faut, je m\u2019attacherai devant la Cour europ\u00e9enne des droits de l&rsquo;homme pour obtenir justice<\/em>\u00a0\u00bb .<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d66915366f6cf64afa347c6cc712ca90 wp-block-paragraph\">C\u00e9dric Prizzon \u00e9tait tellement mena\u00e7ant qu&rsquo;en 2019 il a \u00e9t\u00e9 condamn\u00e9 \u00e0 9 mois ferme pour non pr\u00e9sentation d&rsquo;enfant apr\u00e8s une premi\u00e8re cavale en Espagne, puis en 2022 il a \u00e9cop\u00e9 de 6 mois de sursis pour des menaces de mort contre la m\u00e8re de son fils (c&rsquo;\u00e9tait \u00e7a la \u00ab\u00a0grave erreur judiciaire\u00a0\u00bb&nbsp;: les gens qui ont minimis\u00e9 ou banalis\u00e9 ses menaces de mort en pensant qu&rsquo;elles n&rsquo;\u00e9taient que des paroles en l&rsquo;air prononc\u00e9es sous le coup de la col\u00e8re devraient aujourd&rsquo;hui s&rsquo;\u00e9touffer dans leur honte), et enfin en d\u00e9cembre 2024 il a encore \u00e9t\u00e9 condamn\u00e9 pour harc\u00e8lement sur ex-conjoint. Bref, c&rsquo;\u00e9tait le genre d&rsquo;ex dont les femmes savent qu&rsquo;il est capable de tout et qu&rsquo;avec lui il faut toujours rester sur ses gardes, le genre d&rsquo;ex dont on continue \u00e0 \u00eatre terroris\u00e9e et que l&rsquo;on ne quitte jamais tout \u00e0 fait, car il sait tr\u00e8s bien s&rsquo;y prendre pour maintenir la relation d&#8217;emprise en faisant planer une menace sur elle (et bien souvent sur les enfants).<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-65874d61ad46bbceedddfb606e5a72bd wp-block-paragraph\">Finalement, comme son ex-femme, la famille et les ami\u00b7es de celle-ci le craignaient, C\u00e9dric Prizzon est effectivement all\u00e9 \u00ab\u00a0jusqu&rsquo;au bout\u00a0\u00bb, et il a d\u00e9cid\u00e9 de se faire justice lui-m\u00eame, en mettant de fait son fils \u00ab\u00a0en grave danger\u00a0\u00bb. Il a enlev\u00e9 son ex-compagne et son actuelle compagne, puis il les a \u00e9touff\u00e9es l&rsquo;une apr\u00e8s l&rsquo;autre (la seconde parce qu&rsquo;elle lui demandait de se rendre), et dans les deux cas il a commis ces abominations sous les yeux de son fils de 12 ans, \u00e0 qui il a ensuite ordonn\u00e9 de \u00ab\u00a0monter la garde\u00a0\u00bb pendant qu&rsquo;il allait enterrer les corps. Il y a un moment o\u00f9 les mots manquent pour dire \u00e0 quel point certains membres de l&rsquo;esp\u00e8ce humaine sont des pourritures.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"886\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Cedric-Plizzon-muscu.jpg\" alt=\"\" class=\"wp-image-15192\" style=\"width:270px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Cedric-Plizzon-muscu.jpg 500w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Cedric-Plizzon-muscu-169x300.jpg 169w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Cedric-Plizzon-muscu-350x620.jpg 350w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Cedric-Plizzon-muscu-367x650.jpg 367w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Cedric-Plizzon-muscu-254x450.jpg 254w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-812797bf3dd2d3609ba4898fa622d570 wp-block-paragraph\">Bien s\u00fbr on est tent\u00e9 de chercher des explications individuelles \u00e0 ce \u00e9ni\u00e8me cas de f\u00e9minicide. Bien s\u00fbr il y a des raisons personnelles qui font que C\u00e9dric Prizzon est devenu un tueur. Pas besoin d&rsquo;\u00eatre champion olympique de psychologie et d&#8217;empathie pour deviner qu&rsquo;il a s\u00fbrement \u00e9t\u00e9 \u00e9lev\u00e9 \u00ab\u00a0\u00e0 la dure\u00a0\u00bb (\u00e0 ce que la psychoth\u00e9rapeute Alice Miller appelle la \u00ab\u00a0<em>p\u00e9dagogie noire<\/em>\u00a0\u00bb \u2013 vous savez, celle dont \u00ab\u00a0on ne meurt pas\u00a0\u00bb, tu parles). Pas besoin de sortir de Saint-Cyr pour deviner que cet ancien policier aimait que les choses soient en ordre, que \u00e7a file droit, que ce soit aussi carr\u00e9 que sa m\u00e2choire. J&rsquo;imagine aussi qu&rsquo;il \u00e9tait de ceux qui pensent que la France irait mieux si on matait les sauvageons et si on virait les bougnoules, les p\u00e9d\u00e9s et les woke, allez. En tous cas il \u00e9tait aussi amateur de musculation et de bagnoles (sur son compte Instagram, \u00ab\u00a0<em>il alternait les photos de voitures et celles o\u00f9 il se mettait en sc\u00e8ne en train de soulever de la fonte<\/em>\u00a0\u00bb )&nbsp;: je ne dis pas que \u00e7a soit forc\u00e9ment le signe d&rsquo;une tare irr\u00e9parable, mais enfin quand on met \u00e7a en rapport avec le reste du tableau, c&rsquo;est plut\u00f4t un indicateur de plus du fait que C\u00e9dric Prizzon \u00e9tait un gros beauf.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-b7d84395a3c14a655a61b108c51aecad wp-block-paragraph\">Mais le meurtre qu&rsquo;il a commis n&rsquo;est pas le r\u00e9sultat d&rsquo;une \u00ab\u00a0d\u00e9rive\u00a0\u00bb, contrairement \u00e0 ce que dit le titre de <a href=\"https:\/\/www.lemonde.fr\/societe\/article\/2026\/03\/25\/double-feminicide-presume-la-derive-de-cedric-p-des-manifestations-devant-les-tribunaux-a-l-enlevement-de-son-ex-compagne_6674270_3224.html\" data-type=\"link\" data-id=\"https:\/\/www.lemonde.fr\/societe\/article\/2026\/03\/25\/double-feminicide-presume-la-derive-de-cedric-p-des-manifestations-devant-les-tribunaux-a-l-enlevement-de-son-ex-compagne_6674270_3224.html\">cet article du <em>Monde<\/em><\/a>. Il ne s&rsquo;agit pas d&rsquo;un type qui, pour des raisons obscures et peu compr\u00e9hensibles, serait sorti du droit chemin dans lequel se tiennent tous les autres hommes \u00ab\u00a0normaux\u00a0\u00bb, ceux qui ne frappent pas, qui ne violent pas et qui ne tuent pas les femmes. C\u00e9dric Prizzon n&rsquo;est pas une \u00ab\u00a0erreur\u00a0\u00bb&nbsp;: il est un \u00ab\u00a0bon soldat\u00a0\u00bb et m\u00eame un \u00ab\u00a0bon \u00e9l\u00e8ve\u00a0\u00bb du <a href=\"https:\/\/gregoryderville.com\/index.php\/tag\/feminisme-partriarcat\/\" data-type=\"link\" data-id=\"https:\/\/gregoryderville.com\/index.php\/tag\/feminisme-partriarcat\/\">patriarcat <\/a>(selon une formule que j&rsquo;ai lue il y a 2-3 ans mais dont je n&rsquo;arrive plus \u00e0 me souvenir de la source), c&rsquo;est-\u00e0-dire qu&rsquo;il est un homme qui a appris sagement et r\u00e9p\u00e9t\u00e9 de fa\u00e7on scrupuleuse la le\u00e7on que le patriarcat s&#8217;emploie \u00e0 incruster dans le cr\u00e2ne de tous les petits gar\u00e7ons. C&rsquo;est un homme qui a appris \u00e0 ob\u00e9ir aux figures masculines dominantes et aux r\u00e9cits dominants qui mart\u00e8lent qu&rsquo;un homme un vrai c&rsquo;est solidement charpent\u00e9, \u00e7a ne chiale pas comme une gonzesse, \u00e7a ne montre pas de faiblesse, \u00e7a n&rsquo;a pas peur, \u00e7a ne se laisse pas marcher sur les pieds, \u00e7a reste droit dans ses bottes, \u00e7a s&rsquo;impose, \u00e7a \u00e9crase, \u00e7a domine, \u00e7a commande, \u00e7a m\u00e9prise. Que l&rsquo;homme est sup\u00e9rieur \u00e0 la femme (ne dit-on pas que \u00ab\u00a0le masculin l&#8217;emporte sur le f\u00e9minin\u00a0\u00bb? La femme n&rsquo;est-elle pas une cr\u00e9ature ch\u00e9tive et fragile qui a besoin d&rsquo;un homme pour qu&rsquo;il la \u00ab\u00a0prot\u00e8ge\u00a0\u00bb \u2013 mais la prot\u00e9ger de qui sinon d&rsquo;autres hommes, Ducon?). C\u00e9dric Prizzon a bien appris la le\u00e7on du patriarcat qui r\u00e9p\u00e8te partout de fa\u00e7on insidieuse que l&rsquo;homme a plus de valeur que la femme, qu&rsquo;il a davantage de droits qu&rsquo;elle, et qu&rsquo;il a m\u00eame des droits <em>sur elle<\/em>, y compris le droit de lui dire que personne ne l&rsquo;aimera jamais comme lui l&rsquo;aime et que sans lui elle n&rsquo;est rien, y compris le droit de la traiter de salope et de l&#8217;emp\u00eacher de \u00ab\u00a0refaire sa vie\u00a0\u00bb lorsqu&rsquo;elle trouve enfin la force de le quitter, y compris le droit de lui faire payer et de faire payer \u00e0 \u00ab\u00a0ses\u00a0\u00bb enfants le fait qu&rsquo;elle le quitte, et m\u00eame, pourquoi pas, le droit de la rayer de la surface de la terre. Il \u00e9tait l&rsquo;arch\u00e9type du \u00ab\u00a0vrai mec\u00a0\u00bb, c&rsquo;est-\u00e0-dire du mec convaincu qu&rsquo;un homme un vrai c&rsquo;est solidement charpent\u00e9, \u00e7a ne chiale pas comme une gonzesse, \u00e7a ne montre pas de faiblesse, \u00e7a n&rsquo;a pas peur, \u00e7a ne se laisse pas marcher sur les pieds, \u00e7a reste droit dans ses bottes, \u00e7a s&rsquo;impose, \u00e7a \u00e9crase, \u00e7a domine, \u00e7a commande, \u00e7a m\u00e9prise\u2026 et quand \u00e7a se sent pris en faute, quand \u00e7a se sent rejet\u00e9, eh bien \u00e7a attaque, et m\u00eame \u00e7a tue. Il y a un continuum entre tout cela, de m\u00eame qu&rsquo;il y a un continuum des violences conjugales entre le m\u00e9pris, les attaques verbales, le contr\u00f4le coercitif, le chantage au sexe, les insultes, les coups, le viol conjugal, et le f\u00e9minicide.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8b99e7db57be7c27c5787797f4c22c40 wp-block-paragraph\">Pour le dire plus simplement: le patriarcat tue.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2ff3c6c5f529dc500789fd2de3e62eb0 wp-block-paragraph\">Je suis all\u00e9 jeter un \u0153il au contenu du groupe Facebook \u00ab\u00a0Papas en col\u00e8re\u00a0\u00bb \ud83e\udd2e, et plusieurs jours apr\u00e8s l&rsquo;arrestation de C\u00e9dric Prizzon au Portugal, il n&rsquo;y a toujours pas le moindre message ni le moindre commentaire pour se d\u00e9solidariser de cet homme et pour souligner le fait que ce qu&rsquo;il a commis est une monstruosit\u00e9. On trouve sur ce groupe un flot de messages d&rsquo;hommes qui, eux aussi, se plaignent de leur ex-femme ou compagne pr\u00e9tendument \u00ab\u00a0folle\u00a0\u00bb, \u00ab\u00a0instable\u00a0\u00bb ou \u00ab\u00a0sournoise\u00a0\u00bb, accusent la soci\u00e9t\u00e9 et la Justice de leur avoir vol\u00e9 \u00ab\u00a0leurs\u00a0\u00bb enfants, d\u00e9noncent une soci\u00e9t\u00e9 domin\u00e9e par les femmes et dans laquelle les p\u00e8res n&rsquo;ont plus aucun droit. Bien s\u00fbr aucun d&rsquo;eux n&rsquo;\u00e9crit la moindre ligne laissant entendre qu&rsquo;il pourrait avoir une quelconque responsabilit\u00e9 dans le fait que ses enfants ne le voient plus et\/ou ne veulent plus le voir. Selon eux c&rsquo;est forc\u00e9ment la preuve que leurs enfants ont \u00e9t\u00e9 \u00ab\u00a0manipul\u00e9s\u00a0\u00bb ou \u00ab\u00a0embrigad\u00e9s\u00a0\u00bb par leur m\u00e8re (dans l&rsquo;un des nombreux messages haineux pr\u00e9sents sur son compte FB, C\u00e9dric Prizzon accusait la m\u00e8re de son fils de \u00ab\u00a0<em>forcer notre enfant \u00e0 mentir<\/em>\u00a0\u00bb ). En r\u00e9alit\u00e9, presque toujours, c&rsquo;est tout simplement la cons\u00e9quence logique du fait que depuis la naissance de leurs enfants, ils se sont totalement d\u00e9charg\u00e9s de leur \u00e9ducation sur leur compagne et ils ont \u00e9t\u00e9 infoutus d&rsquo;\u00eatre des p\u00e8res ne serait-ce que vaguement corrects&#8230; Je ne suis rest\u00e9 que quelques minutes \u00e0 lire les posts de ce groupe, et quand j&rsquo;en suis sorti je ressentais une immense col\u00e8re contre ces hommes qui se pr\u00e9sentent comme des victimes et qui se croient \u00eatre courageux alors que ce ne sont que des tocards, des minables et des brutes \u00e9paisses.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1c30a634d93b5918c1ddceb1e2a2c761 wp-block-paragraph\">Je pense \u00e0 tous ces jeunes gar\u00e7ons et adolescents qui biberonnent \u00e0 des comptes masculinistes ou \u00e0 des pages Tik-tok de \u00ab\u00a0coaches en s\u00e9duction\u00a0\u00bb qui leur vissent dans le cr\u00e2ne qu&rsquo;une femme dont le \u00ab\u00a0bodycount\u00a0\u00bb est trop \u00e9lev\u00e9 ne m\u00e9rite pas le respect, que \u00ab\u00a0la femme\u00a0\u00bb a envie d&rsquo;\u00eatre domin\u00e9e, qu&rsquo;un homme qui ne domine pas n&rsquo;est pas un \u00ab\u00a0vrai mec\u00a0\u00bb, que m\u00eame quand une femme dit non en fait elle pense oui, etc. Parmi eux, combien deviendront des C\u00e9dric Prizzon&nbsp;? Et combien de femmes verront leur vie pourrie, massacr\u00e9e, an\u00e9antie par ces futurs despotes&nbsp;? \u00c7a fait partie de la longue, tr\u00e8s longue liste des choses qui m&rsquo;angoissent quand je pense \u00e0 l&rsquo;avenir.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Feminicide-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"349\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Feminicide-1.jpg\" alt=\"\" class=\"wp-image-15194\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Feminicide-1.jpg 700w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Feminicide-1-300x150.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Feminicide-1-600x299.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Feminicide-1-400x199.jpg 400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n<\/div><!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID15190\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"15190\"\n         id=\"da-reactions-slot-post-15190\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Deux de plus. Une fois de plus, le patriarcat a tu\u00e9 en France. En 2004, les forces de l&rsquo;ordre ont enregistr\u00e9 en France 107 victimes de f\u00e9minicides au sein du&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2026\/03\/27\/le-feminicide-est-le-produit-du-patriarcat\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">Le f\u00e9minicide est le produit du patriarcat<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID15190\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"15190\"\n         id=\"da-reactions-slot-post-15190\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":15195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[86],"tags":[63],"class_list":["post-15190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe","tag-feminisme-partriarcat"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/15190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=15190"}],"version-history":[{"count":20,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/15190\/revisions"}],"predecessor-version":[{"id":15233,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/15190\/revisions\/15233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/15195"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=15190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=15190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=15190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}