{"id":15272,"date":"2026-03-30T16:50:58","date_gmt":"2026-03-30T14:50:58","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=15272"},"modified":"2026-03-30T21:12:06","modified_gmt":"2026-03-30T19:12:06","slug":"petrole-penurie-et-rationnement-tic-tac-tic-tac-tic-tac","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2026\/03\/30\/petrole-penurie-et-rationnement-tic-tac-tic-tac-tic-tac\/","title":{"rendered":"P\u00e9trole, p\u00e9nurie et rationnement: tic tac tic tac tic tac"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-c7a781b106a378e74018ad6a2e769804 wp-block-paragraph\">En 1973, l&rsquo;une des plus c\u00e9l\u00e8bres campagnes de communication institutionnelle de l&rsquo;\u00c9tat fran\u00e7ais proclamait qu&rsquo; \u00ab\u00a0<em>En France on n&rsquo;a pas de p\u00e9trole, mais on a des id\u00e9es<\/em>.\u00a0\u00bb<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d489ec2a2a6a37847dece64aa7121383 wp-block-paragraph\">Il y a quatre ans, apr\u00e8s que la guerre en Ukraine a d\u00e9clench\u00e9 une envol\u00e9e des prix des <a href=\"https:\/\/gregoryderville.com\/index.php\/tag\/energie\/\" data-type=\"link\" data-id=\"https:\/\/gregoryderville.com\/index.php\/tag\/energie\/\">\u00e9nergies fossiles<\/a> et notamment du gaz, l&rsquo;\u00c9tat fran\u00e7ais incitait \u00e0 modifier les habitudes individuelles (ah, cet in\u00e9narrable slogan \u00ab\u00a0<em>Je baisse, j&rsquo;\u00e9teins, je d\u00e9cale<\/em>\u00a0\u00bb ), et son ministre des Finances conseillait de porter des pulls \u00e0 col roul\u00e9. Comme c&rsquo;\u00e9tait malheureusement pr\u00e9visible, une fois le plus fort de la crise retomb\u00e9e, non seulement l&rsquo;\u00c9tat n&rsquo;a pas fait grand chose pour accentuer la sortie des \u00e9nergies fossiles, mais il a m\u00eame d\u00e9mantel\u00e9 tout ou partie de nombreux dispositifs qui visent \u00e0 atteindre cet objectif&nbsp;: par exemple la partie du \u00ab\u00a0plan v\u00e9lo\u00a0\u00bb financ\u00e9e sur le budget de l&rsquo;\u00c9tat a fondu de 250 \u00e0 50&nbsp;millions d&rsquo;euros en 2025, l&rsquo;enveloppe budg\u00e9taire consacr\u00e9e \u00e0 MaPrimeRenov&rsquo; est tomb\u00e9e de 5 \u00e0 3,5&nbsp;milliards d&rsquo;euros en 2024 (avant que cette prime soit carr\u00e9ment gel\u00e9e \u00e0 l&rsquo;\u00e9t\u00e9 2025), la limitation \u00e0 80 km\/h sur route a \u00e9t\u00e9 abandonn\u00e9e en rase campagne (c&rsquo;est le cas de le dire)\u2026<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Pas-de-petrole-mais-des-idees.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"670\" data-id=\"15274\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Pas-de-petrole-mais-des-idees.jpg\" alt=\"\" class=\"wp-image-15274\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Pas-de-petrole-mais-des-idees.jpg 768w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Pas-de-petrole-mais-des-idees-300x262.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Pas-de-petrole-mais-des-idees-711x620.jpg 711w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Pas-de-petrole-mais-des-idees-600x523.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Pas-de-petrole-mais-des-idees-400x349.jpg 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Jeteins-je-baisse-je-decale.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"352\" height=\"363\" data-id=\"15288\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Jeteins-je-baisse-je-decale.jpeg\" alt=\"\" class=\"wp-image-15288\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Jeteins-je-baisse-je-decale.jpeg 352w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Jeteins-je-baisse-je-decale-291x300.jpeg 291w\" sizes=\"auto, (max-width: 352px) 100vw, 352px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-c0fd05cf727d9108dbc6cc1e89dea996 wp-block-paragraph\">Avec l&rsquo;attaque des \u00c9tats-Unis contre l&rsquo;Iran, une autre crise g\u00e9opolitique met \u00e0 nouveau sous pression l&rsquo;approvisionnement du monde en hydrocarbures et pousse fortement \u00e0 la hausse le prix du p\u00e9trole (et derri\u00e8re le prix de la plupart des produits et les services, \u00e0 commencer bien s\u00fbr par les carburants).<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-d18b7fd70157cdbb5e72786ccf180c0e wp-block-paragraph\">\u00ab\u00a0Qui aurait pu pr\u00e9dire&nbsp;?\u00a0\u00bb<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-73432746a59e7e4fe475fd70f1689cbb wp-block-paragraph\">En tous cas \u00e0 en juger par les mesures prises par de nombreux pays asiatiques pour r\u00e9duire la consommation, et \u00e0 en juger par celles qu&rsquo;envisage le gouvernement anglais (un <a href=\"https:\/\/gregoryderville.com\/index.php\/tag\/penuries\/\" data-type=\"link\" data-id=\"https:\/\/gregoryderville.com\/index.php\/tag\/penuries\/\">rationnement<\/a>, dans un pays europ\u00e9en!), cette fois-ci la douloureuse pourrait \u00eatre plus sal\u00e9e, surtout si la situation dans le golfe continuer \u00e0 s&#8217;embourber (ce qui semble pour l&rsquo;instant le scenario le plus plausible, en d\u00e9pit des tartarinades du clown sinistre qui sert d&rsquo;apprenti dictateur \u00e0 la premi\u00e8re puissance \u00e9conomique du monde).<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-0e611e228af2d54829b1590fe0a88491 wp-block-paragraph\">Est-ce qu&rsquo;il ne serait pas enfin temps de s&rsquo;engager r\u00e9solument dans une politique de sortie des \u00e9nergies fossiles&nbsp;?<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-b1b485a2097d84439224ce26cecd215b wp-block-paragraph\">Plus encore, est-ce qu&rsquo;il ne serait pas enfin temps de s&rsquo;engager r\u00e9solument dans une (des) politique(s) de SOBRI\u00c9T\u00c9 (et pas seulement dans une fuite en avant techno-solutionniste)\u00a0?<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5c5ce6c88df6e531ecf2ab848c2fdb4d wp-block-paragraph\">Il est de plus en plus \u00e9vident que nous ne pourrons pas \u00e9viter, que nous le voulions ou non, une transformation radicale de l&rsquo;ensemble de la soci\u00e9t\u00e9\u00a0: des modes de d\u00e9placement mais aussi de l&rsquo;am\u00e9nagement du territoire, des pratiques agricoles, du BTP, et de la r\u00e9glementation dans \u00e0 peu pr\u00e8s tous les domaines (politiques en faveur d&rsquo;une alimentation moins carn\u00e9e, lutte contre l&rsquo;obsolescence programm\u00e9e, r\u00e9duction du volume de d\u00e9chets et d\u00e9veloppement du compostage et du r\u00e9emploi, diminution massive de la consommation de plastique, etc.). Si tout cela n&rsquo;est pas fait de fa\u00e7on \u00e0 la fois tr\u00e8s ambitieuse &#8211; ou radicale &#8211; ET juste socialement, cette crise et les suivantes seront de plus en plus violentes, et elles entra\u00eeneront des cons\u00e9quences de plus en plus graves, notamment pour les personnes et les groupes sociaux les plus fragiles.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"327\" height=\"357\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Suicide-au-petrole.jpg\" alt=\"\" class=\"wp-image-15275\" style=\"width:315px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Suicide-au-petrole.jpg 327w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/03\/Suicide-au-petrole-275x300.jpg 275w\" sizes=\"auto, (max-width: 327px) 100vw, 327px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-460d457f4eb5176376ce4b2acd2c92e1 wp-block-paragraph\">Pour mener \u00e0 bien cette transformation sociale, qui est aussi vitale pour des raisons \u00e9cologiques (changement climatique, effondrement de la biodiversit\u00e9, pollutions diverses et vari\u00e9es&#8230;), les projets sont innombrables, et pendant encore un peu de temps nous avons les moyens mat\u00e9riels de les d\u00e9velopper. Mais si nous ne faisons pas ce qui doit l&rsquo;\u00eatre, bient\u00f4t nous prendrons de plein fouet des crises g\u00e9opolitiques, \u00e9cologiques et sociales qui s&rsquo;entrem\u00ealent de fa\u00e7on inextricable, et nous les prendrons de plein fouet sans aucune ressource pour y r\u00e9pondre. Plus que jamais, l&rsquo;alternative est entre une sortie \u00e0 peu pr\u00e8s ordonn\u00e9e de la soci\u00e9t\u00e9 thermo-industrielle, et un <a href=\"https:\/\/gregoryderville.com\/index.php\/tag\/effondrement-collapse\/\" data-type=\"link\" data-id=\"https:\/\/gregoryderville.com\/index.php\/tag\/effondrement-collapse\/\">effondrement <\/a>brutal, violent et injuste.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-31377588fbacbf990b06a7b05cb0fda8 wp-block-paragraph\">Tic tac tic tac tic tac\u2026<\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID15272\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"15272\"\n         id=\"da-reactions-slot-post-15272\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En 1973, l&rsquo;une des plus c\u00e9l\u00e8bres campagnes de communication institutionnelle de l&rsquo;\u00c9tat fran\u00e7ais proclamait qu&rsquo; \u00ab\u00a0En France on n&rsquo;a pas de p\u00e9trole, mais on a des id\u00e9es.\u00a0\u00bb Il y a&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2026\/03\/30\/petrole-penurie-et-rationnement-tic-tac-tic-tac-tic-tac\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">P\u00e9trole, p\u00e9nurie et rationnement: tic tac tic tac tic tac<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID15272\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"15272\"\n         id=\"da-reactions-slot-post-15272\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":15294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88,85,86],"tags":[97,700,713],"class_list":["post-15272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecologie","category-politique","category-societe","tag-effondrement-collapse","tag-energie","tag-penuries"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/15272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=15272"}],"version-history":[{"count":14,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/15272\/revisions"}],"predecessor-version":[{"id":15300,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/15272\/revisions\/15300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/15294"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=15272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=15272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=15272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}