{"id":15370,"date":"2026-04-14T21:12:54","date_gmt":"2026-04-14T19:12:54","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=15370"},"modified":"2026-04-14T21:20:19","modified_gmt":"2026-04-14T19:20:19","slug":"lorvet-un-drole-de-lezard-sans-pattes","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2026\/04\/14\/lorvet-un-drole-de-lezard-sans-pattes\/","title":{"rendered":"L&rsquo;orvet, un dr\u00f4le de l\u00e9zard sans pattes"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-6293cd65768f0de8426e04c7b3bf0d62 wp-block-paragraph\">Depuis 6 ans que je suis install\u00e9 en Limousin, je n&rsquo;ai vu qu&rsquo;une seule fois un orvet sur mon terrain : c&rsquo;\u00e9tait l&rsquo;ann\u00e9e derni\u00e8re, pendant que je creusais un gros trou pour planter un arbre fruitier&#8230; et malheureusement un coup de b\u00eache venait de le couper en deux \ud83d\ude14<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-bc42c7ad859291710daa1a5a41192605 wp-block-paragraph\">Il y a quelques jours j&rsquo;en ai vu un deuxi\u00e8me, mais celui-ci se d\u00e9pla\u00e7ait souplement dans l&rsquo;herbe. Le temps de lui faire prendre la pose pour une petite photo, et le voil\u00e0 reparti entre les pieds de m\u00e2che qui sont en train de monter en fleurs. Depuis il a peut-\u00eatre crois\u00e9 le chemin de deux autres reptiles qui vivent chez moi et que j&rsquo;ai \u00e0 nouveau rencontr\u00e9s ces jours-ci dans mon jardin, comme chaque printemps: le l\u00e9zard vert, et la couleuvre verte et jaune.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-8057f3e2359701f5a292c0577e7776a3 wp-block-paragraph\">L&rsquo;orvet&nbsp;fragile (<em>Anguis fragilis<\/em>) est un reptile qui ressemble aux serpents, mais qui n&rsquo;en est pas un : c&rsquo;est un l\u00e9zard qui, dans la longue odyss\u00e9e de l&rsquo;\u00e9volution, a perdu ses pattes. Il mesure entre 40 cm et 45 cm, rarement plus. Sa peau est brillante car il est couvert d&rsquo;\u00e9cailles tr\u00e8s lisses, ce qui lui donne un contact froid et doux. C\u2019est un animal totalement inoffensif, d\u00e9pourvu de venin, et qui n&rsquo;essaie m\u00eame pas de mordiller. Pour le saisir, il faut faire tr\u00e8s attention car sa queue est tr\u00e8s fragile, et si elle se casse elle ne se reconstitue pas, donc il meurt irr\u00e9m\u00e9diablement&#8230;<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-b28731e06e8567aaf97b422ccfeef036 wp-block-paragraph\">L&rsquo;orvet passe l&rsquo;essentiel de son temps dans la v\u00e9g\u00e9tation (de pr\u00e9f\u00e9rence assez dense, ombrag\u00e9e et l\u00e9g\u00e8rement humide), car \u00e7a lui permet d&rsquo;\u00eatre \u00e0 l&rsquo;abri des pr\u00e9dateurs. Il aime les haies, les clairi\u00e8res, les lisi\u00e8res de bois, les bords de plans d&rsquo;eau, les vieilles souches, les foss\u00e9s, les tas de feuilles mortes, les foug\u00e8res, les ronciers&#8230; Il appr\u00e9cie plus encore les jardins, particuli\u00e8rement les paillis et les tas de compost, d&rsquo;autant plus qu&rsquo;il y trouve sa nourriture : c&rsquo;est un pr\u00e9dateur carnivore qui mange principalement des insectes vari\u00e9s, des araign\u00e9es, des vers&#8230; mais aussi et surtout des limaces ou des escargots de petite taille, ainsi que leurs oeufs &#8211; autant dire qu&rsquo;il est l&rsquo;ami des jardiniers!<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-e0091a6f3a0daefa7519f9df4841b176 wp-block-paragraph\">L&rsquo;orvet est un reptile \u00ab\u00a0semi-fouisseur\u00a0\u00bb, qui passe une bonne partie de son temps sous la terre, dans des galeries (notamment celles des rongeurs, mais il peut aussi en creuser lui-m\u00eame). Il ne sort que quand la m\u00e9t\u00e9o est plut\u00f4t humide, ou a minima en dehors des heures o\u00f9 le soleil tape dur.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4497aa629694b876aa6e249de66311a9 wp-block-paragraph\">Il peut vivre plusieurs dizaines d&rsquo;ann\u00e9es, para\u00eet-il jusqu&rsquo;\u00e0 40 ans \ud83d\ude2f Il hiberne sous la terre, \u00e0 partir d\u2019octobre, dans un trou ou un terrier qu&rsquo;il creuse et am\u00e9nage lui-m\u00eame, dans un sol de pr\u00e9f\u00e9rence meuble et frais (il peut descendre jusqu\u2019\u00e0 70 cm de profondeur). Il arrive aussi qu&rsquo;il passe l&rsquo;hiver sous une botte de foin, ou dans un tas de feuilles mortes, ou dans un tas de compost&#8230;<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5eabfb63abc49c554bccf3015f96bb7d wp-block-paragraph\">L&rsquo;orvet est prot\u00e9g\u00e9 par un arr\u00eat\u00e9 du 19 novembre 2007: il est interdit de le tuer, de le capturer, mais aussi de d\u00e9truire son nid. En d\u00e9pit de cette protection, les populations d\u2019orvets fragiles sont un fort d\u00e9clin. Les causes ? Devinez ! 1) l\u2019agriculture intensive, l&#8217;empoisonnement par les pesticides ; 2) l&rsquo;urbanisation et l\u2019augmentation de la circulation automobile ; et 3) la peur des serpents, qui fait que beaucoup tuent les orvets sans m\u00eame savoir que ce sont des animaux non seulement sans danger mais tr\u00e8s utiles.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-eb541baebdfbc52b41f2881e2106726c wp-block-paragraph\">Personnellement j&rsquo;\u00e9tais tout heureux de voir cette petite bestiole chez moi, et j&rsquo;esp\u00e8re qu&rsquo;elle va s&rsquo;y multiplier!<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-b85502c9c1bba06e5db8765bebaf048d wp-block-paragraph\">Ma principale source pour r\u00e9diger ce post est <a href=\"https:\/\/www.lpo.fr\/decouvrir-la-nature\/fiches-especes\/fiches-especes\/amphibiens-reptiles\/orvet-fragile\" data-type=\"link\" data-id=\"https:\/\/www.lpo.fr\/decouvrir-la-nature\/fiches-especes\/fiches-especes\/amphibiens-reptiles\/orvet-fragile\">l&rsquo;article consacr\u00e9 \u00e0 l&rsquo;orvet fragile sur le site de la LPO<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/04\/Orvet-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/04\/Orvet-2.jpg\" alt=\"\" class=\"wp-image-15372\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/04\/Orvet-2.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/04\/Orvet-2-300x200.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/04\/Orvet-2-400x267.jpg 400w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n<\/div><!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID15370\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"15370\"\n         id=\"da-reactions-slot-post-15370\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Depuis 6 ans que je suis install\u00e9 en Limousin, je n&rsquo;ai vu qu&rsquo;une seule fois un orvet sur mon terrain : c&rsquo;\u00e9tait l&rsquo;ann\u00e9e derni\u00e8re, pendant que je creusais un gros&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2026\/04\/14\/lorvet-un-drole-de-lezard-sans-pattes\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">L&rsquo;orvet, un dr\u00f4le de l\u00e9zard sans pattes<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID15370\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"15370\"\n         id=\"da-reactions-slot-post-15370\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":15371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[685],"tags":[694],"class_list":["post-15370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-natureanilaux","tag-reptiles"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/15370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=15370"}],"version-history":[{"count":7,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/15370\/revisions"}],"predecessor-version":[{"id":15404,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/15370\/revisions\/15404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/15371"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=15370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=15370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=15370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}