{"id":16036,"date":"2026-06-02T11:14:30","date_gmt":"2026-06-02T09:14:30","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=16036"},"modified":"2026-06-02T11:31:59","modified_gmt":"2026-06-02T09:31:59","slug":"tu-seras-aime-le-jour-ou-tu-pourras-montrer-ta-faiblesse-sans-quun-autre-sen-serve-pour-affirmer-sa-force","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2026\/06\/02\/tu-seras-aime-le-jour-ou-tu-pourras-montrer-ta-faiblesse-sans-quun-autre-sen-serve-pour-affirmer-sa-force\/","title":{"rendered":"\u00ab\u00a0Tu seras aim\u00e9 le jour o\u00f9&#8230;\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\"><br>\u00ab\u00a0<em>Tu seras aim\u00e9 le jour o\u00f9 tu pourras montrer ta faiblesse sans qu&rsquo;un autre s&rsquo;en serve pour affirmer sa force.<\/em>\u00a0\u00bb <\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">Cette phrase de l&rsquo;\u00e9crivain italien Cesare Pavese est l&rsquo;une de celles qui m&rsquo;\u00e9meuvent le plus. Je suis un homme sensible, fragile et vuln\u00e9rable, et il ne me suffit vraiment pas de grand chose pour \u00eatre affect\u00e9, dans un sens ou dans l&rsquo;autre &#8211; pour rire et m&rsquo;amuser comme un gosse, ou pour m&rsquo;angoisser et pleurer comme un m\u00f4me. Si des faibles, des l\u00e2ches, des frustr\u00e9s, des jaloux ou des m\u00e9chants ont envie de me faire du mal en s&rsquo;armant de ce qu&rsquo;ils savent de mes failles, eh bien qu&rsquo;ils y aillent, et que Dieu ait piti\u00e9 d&rsquo;eux (je ne crois pas que Dieu existe, c&rsquo;est juste une formule pour dire que ces gens-l\u00e0 ne valent pas cher).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><a href=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/05\/Pavese-Le-metier-de-vivre.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"823\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/05\/Pavese-Le-metier-de-vivre.jpg\" alt=\"\" class=\"wp-image-16072\" style=\"aspect-ratio:0.6075452139992907;width:301px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/05\/Pavese-Le-metier-de-vivre.jpg 500w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/05\/Pavese-Le-metier-de-vivre-182x300.jpg 182w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/05\/Pavese-Le-metier-de-vivre-377x620.jpg 377w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/05\/Pavese-Le-metier-de-vivre-395x650.jpg 395w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2026\/05\/Pavese-Le-metier-de-vivre-273x450.jpg 273w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-3 wp-block-paragraph\">Malheureusement pour lui, Cesare Pavese n&rsquo;a pas r\u00e9ussi \u00e0 obtenir cette compr\u00e9hension et cet amour bienveillant, protecteur et rassurant qu&rsquo;il d\u00e9sirait ardemment : le 27 ao\u00fbt 1950, \u00e0 pas m\u00eame quarante-deux ans, il s&rsquo;est suicid\u00e9\u00a0dans une chambre d&rsquo;h\u00f4tel de Turin, en laissant sur sa table un mot qui a sans doute retourn\u00e9 le bide de ses proches\u00a0:\u00a0\u00ab\u00a0<em>Je pardonne \u00e0 tout le monde, et \u00e0 tout le monde je demande pardon. \u00c7a va\u00a0? Ne faites pas trop de comm\u00e9rages.<\/em>\u00a0\u00bb Pour lui la coupe \u00e9tait pleine&#8230; Deux ans plus tard, la phrase que je mets en exergue paraissait de fa\u00e7on posthume dans son journal intime, qui sera baptis\u00e9 <em>Le m\u00e9tier de vivre<\/em>. Dur m\u00e9tier, certains jours&#8230;<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4 wp-block-paragraph\">Heureusement, il y a aussi des jours o\u00f9 vivre n&rsquo;est pas un m\u00e9tier laborieux, douloureux, d\u00e9courageant ou \u00e9reintant, mais une aventure passionnante et excitante, dans laquelle on se plonge les yeux ouverts et le coeur gonfl\u00e9 de d\u00e9sir et de confiance. Dans mon cas personnel, je crois que si je vis beaucoup plus qu&rsquo;avant selon la deuxi\u00e8me de ces modalit\u00e9s, c&rsquo;est en grande partie parce que je r\u00e9ussis de mieux en mieux \u00e0 accepter et \u00e0 d\u00e9voiler ma fragilit\u00e9, ma sensibilit\u00e9, mon besoin d&rsquo;affection et de connexion. Cette phrase de Cesare Pavese est de celle qui m&rsquo;a donn\u00e9 le courage de me livrer, et quand je pense aux moments de joie que cela m&rsquo;a valu, que cela me vaut et que cela me vaudra encore, j&rsquo;\u00e9prouve une grande gratitude pour cet \u00e9crivain.<\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID16036\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"16036\"\n         id=\"da-reactions-slot-post-16036\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Tu seras aim\u00e9 le jour o\u00f9 tu pourras montrer ta faiblesse sans qu&rsquo;un autre s&rsquo;en serve pour affirmer sa force.\u00a0\u00bb Cette phrase de l&rsquo;\u00e9crivain italien Cesare Pavese est l&rsquo;une de&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2026\/06\/02\/tu-seras-aime-le-jour-ou-tu-pourras-montrer-ta-faiblesse-sans-quun-autre-sen-serve-pour-affirmer-sa-force\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">\u00ab\u00a0Tu seras aim\u00e9 le jour o\u00f9&#8230;\u00a0\u00bb<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID16036\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"16036\"\n         id=\"da-reactions-slot-post-16036\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":16037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[147,134],"tags":[141,53,133],"class_list":["post-16036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-litterature","category-psychologie","tag-litterature","tag-poesie","tag-psychologie"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/16036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=16036"}],"version-history":[{"count":27,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/16036\/revisions"}],"predecessor-version":[{"id":16392,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/16036\/revisions\/16392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/16037"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=16036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=16036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=16036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}