{"id":4548,"date":"2022-12-11T19:27:57","date_gmt":"2022-12-11T18:27:57","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=4548"},"modified":"2025-02-18T19:54:48","modified_gmt":"2025-02-18T18:54:48","slug":"altercoupedumondedefootball-jour-22-didier-ou-larret-du-cul","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2022\/12\/11\/altercoupedumondedefootball-jour-22-didier-ou-larret-du-cul\/","title":{"rendered":"Altercoupedumondedefootball (jour 22) &#8211; \u00ab\u00a0Didier\u00a0\u00bb ou \u00ab\u00a0l&rsquo;arr\u00eat du cul\u00a0\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y a-t-il besoin de raconter le pitch du film \u00ab\u00a0Didier\u00a0\u00bb , d&rsquo;Alain Chabat? Presque tout le monde l&rsquo;a vu et s&rsquo;est amus\u00e9 \u00e0 voir l&rsquo;effarement de Jean-Pierre Bacri lorsqu&rsquo;il se rend compte que l&rsquo;individu improbable qui s&rsquo;est install\u00e9 chez lui sans le pr\u00e9venir n&rsquo;est autre que le chien qu&rsquo;on lui a confi\u00e9, myst\u00e9rieusement converti dans un corps humain.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les extraits du film qui sont les plus souvent cit\u00e9s sont les fameux \u00ab\u00a0<em>On ne sent pas le cul!<\/em>\u00ab\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais il y a aussi quelques s\u00e9quences tr\u00e8s dr\u00f4les o\u00f9 l&rsquo;on voit Alain Chabat pousser un ballon dans tous les sens et \u00e9puiser les jeunes qui essayent de le lui reprendre, rentrer dans ses propres cages avec le ballon dans les mains, faire un \u00ab\u00a0arr\u00eat du cul\u00a0\u00bb dans un match au parc des Princes\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D&rsquo;abord exc\u00e9d\u00e9, le personnage jou\u00e9 par Roland Bacri se prend d&rsquo;affection pour cet \u00eatre \u00e9tonnant, et puisqu&rsquo;il est agent de joueurs et que l&rsquo;\u00e9quipe qui l&#8217;emploie est d\u00e9cim\u00e9e, il d\u00e9cide de lui apprendre les rudiments du football.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin plus pr\u00e9cis\u00e9ment, il <em>essaye<\/em> de lui apprendre les rudiments du football \ud83d\ude01<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/watch\/?v=1785410304854274\">https:\/\/www.facebook.com\/watch\/?v=1785410304854274<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec deux s\u00e9quences cultes du film:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Didier - Didje est pr\u00e9sent\u00e9 \u00e0 l&#039;entraineur\" width=\"1230\" height=\"692\" src=\"https:\/\/www.youtube.com\/embed\/KbouckwAY8s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Didier Arret des fesses\" width=\"1230\" height=\"692\" src=\"https:\/\/www.youtube.com\/embed\/jMzvYMipTao?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID4548\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"4548\"\n         id=\"da-reactions-slot-post-4548\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Y a-t-il besoin de raconter le pitch du film \u00ab\u00a0Didier\u00a0\u00bb , d&rsquo;Alain Chabat? Presque tout le monde l&rsquo;a vu et s&rsquo;est amus\u00e9 \u00e0 voir l&rsquo;effarement de Jean-Pierre Bacri lorsqu&rsquo;il se&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2022\/12\/11\/altercoupedumondedefootball-jour-22-didier-ou-larret-du-cul\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">Altercoupedumondedefootball (jour 22) &#8211; \u00ab\u00a0Didier\u00a0\u00bb ou \u00ab\u00a0l&rsquo;arr\u00eat du cul\u00a0\u00bb<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID4548\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"4548\"\n         id=\"da-reactions-slot-post-4548\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":4777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79,158],"tags":[407],"class_list":["post-4548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinema","category-sport","tag-football"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/4548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=4548"}],"version-history":[{"count":1,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/4548\/revisions"}],"predecessor-version":[{"id":4550,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/4548\/revisions\/4550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/4777"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=4548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=4548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=4548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}