{"id":5181,"date":"2023-09-24T07:53:55","date_gmt":"2023-09-24T05:53:55","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=5181"},"modified":"2025-05-30T18:12:02","modified_gmt":"2025-05-30T16:12:02","slug":"profusion-de-courges-longue-de-nice-cette-annee","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2023\/09\/24\/profusion-de-courges-longue-de-nice-cette-annee\/","title":{"rendered":"Profusion de courges longue de Nice cette ann\u00e9e"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans la s\u00e9rie \u00ab\u00a0Foirages relatifs au jardin\u00a0\u00bb (et donc <a href=\"https:\/\/www.facebook.com\/hashtag\/feelpastoutafaitgoodpost?__eep__=6&amp;__cft__[0]=AZWWrQNanDAGYLAQv84uga6yii8z-lOtOu-ST7z2Fjf-6cnH09SBwYd8BosapTRsdOUcTRIyV1ffmcM_WcmKhml-N_MRe_bal_E8y7xDPU7trsn3XVryofrxzknldsCGrhcpeoGKvKMHmnWn_GWBjIoUIEwMAWL9DiBPjFeOOD8sVutW2Pa8hb_OThtObjECzcw&amp;__tn__=*NK-R\">#Feelpastoutafaitgoodpost<\/a>), apr\u00e8s les pommes de terre nombreuses mais en partie ab\u00eem\u00e9es par le mildiou, voici les courges.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur cette photo, on voit environ les 2 tiers de ma r\u00e9colte de courges de l&rsquo;ann\u00e9e, des Longues de Nice et des Butternut (le reste doit encore m\u00fbrir un peu, et j&rsquo;en ai mang\u00e9 une douzaine \u00ab\u00a0jeunes\u00a0\u00bb pendant l&rsquo;\u00e9t\u00e9).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les plus grosses font plus de 4 kilos, et elles sont excellentes (test\u00e9es avant-hier en pur\u00e9e <a><\/a>avec des pommes de terre).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors pourquoi \u00ab\u00a0foirage relatif\u00a0\u00bb? Parce que&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1) j&rsquo;ai rat\u00e9 les butternuts, sans aucune explication \u00e9vidente. Les quelques-unes que l&rsquo;on voit sur la photo sont un semis spontan\u00e9 issu de compost de surface pendant l&rsquo;hiver. Celles que j&rsquo;ai sem\u00e9es sont petites et pas encore m\u00fbres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2) j&rsquo;avais sem\u00e9 des nombreuses graines de potimarron, qui ont tr\u00e8s bien germ\u00e9 et donn\u00e9 plus de 20 beaux plants. Sauf que&#8230; ce n&rsquo;\u00e9tait pas des potimarrons mais des Longues de Nice (<a href=\"https:\/\/www.facebook.com\/hashtag\/putaingregles%C3%A9tiquettes?__eep__=6&amp;__cft__[0]=AZWWrQNanDAGYLAQv84uga6yii8z-lOtOu-ST7z2Fjf-6cnH09SBwYd8BosapTRsdOUcTRIyV1ffmcM_WcmKhml-N_MRe_bal_E8y7xDPU7trsn3XVryofrxzknldsCGrhcpeoGKvKMHmnWn_GWBjIoUIEwMAWL9DiBPjFeOOD8sVutW2Pa8hb_OThtObjECzcw&amp;__tn__=*NK-R\">#putainGregles\u00e9tiquettes<\/a>) <img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83e\udd74\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tee\/1\/16\/1f974.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83e\udd2a\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t80\/1\/16\/1f92a.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\ude44\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t4e\/1\/16\/1f644.png\"><img loading=\"lazy\" decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83e\udd21\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t50\/1\/16\/1f921.png\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heureusement, les Longues de Nice sont absolument d\u00e9licieuses jeunes (bien meilleures que les courgettes \u00e0 mon go\u00fbt), et en conservation longue j&rsquo;aime aussi beaucoup.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Coup de bol que j&rsquo;aime \u00e7a moi!\u00a0\u00bb (<a href=\"https:\/\/www.facebook.com\/hashtag\/putaingregles%C3%A9tiquettes?__eep__=6&amp;__cft__[0]=AZWWrQNanDAGYLAQv84uga6yii8z-lOtOu-ST7z2Fjf-6cnH09SBwYd8BosapTRsdOUcTRIyV1ffmcM_WcmKhml-N_MRe_bal_E8y7xDPU7trsn3XVryofrxzknldsCGrhcpeoGKvKMHmnWn_GWBjIoUIEwMAWL9DiBPjFeOOD8sVutW2Pa8hb_OThtObjECzcw&amp;__tn__=*NK-R\">#philippetimsitsorsdececorps<\/a>), parce que je crois que je vais en bouffer (pur\u00e9e, soupe, frites, gratin&#8230;).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\/\/\/\/\/\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour tout savoir ou presque sur les courges, leur origine, leur culture, leur conservation, leur utilisation culinaire, <a href=\"https:\/\/www.fermedesaintemarthe.com\/blogs\/comment-reussir-la-culture-de\/reussir-la-culture-de-la-courge?srsltid=AfmBOopZAyoRd2sZ3nQAhCHoIhaetfwioqSrHKsXVlffOkwfkiMkNlDR\" data-type=\"link\" data-id=\"https:\/\/www.fermedesaintemarthe.com\/blogs\/comment-reussir-la-culture-de\/reussir-la-culture-de-la-courge?srsltid=AfmBOopZAyoRd2sZ3nQAhCHoIhaetfwioqSrHKsXVlffOkwfkiMkNlDR\">cet article de la Ferme Sainte-Marthe<\/a> est tr\u00e8s bien fait.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID5181\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"5181\"\n         id=\"da-reactions-slot-post-5181\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans la s\u00e9rie \u00ab\u00a0Foirages relatifs au jardin\u00a0\u00bb (et donc #Feelpastoutafaitgoodpost), apr\u00e8s les pommes de terre nombreuses mais en partie ab\u00eem\u00e9es par le mildiou, voici les courges. Sur cette photo, on&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2023\/09\/24\/profusion-de-courges-longue-de-nice-cette-annee\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">Profusion de courges longue de Nice cette ann\u00e9e<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID5181\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"5181\"\n         id=\"da-reactions-slot-post-5181\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":5182,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[71,651,72],"class_list":["post-5181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jardin","tag-jardin","tag-legumes","tag-recoltes"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/5181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=5181"}],"version-history":[{"count":2,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/5181\/revisions"}],"predecessor-version":[{"id":10200,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/5181\/revisions\/10200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/5182"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=5181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=5181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=5181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}