{"id":5380,"date":"2022-10-28T16:09:27","date_gmt":"2022-10-28T14:09:27","guid":{"rendered":"https:\/\/gregoryderville.com\/?p=5380"},"modified":"2025-03-09T08:53:32","modified_gmt":"2025-03-09T07:53:32","slug":"le-chou-petai-lun-de-mes-choux-preferes","status":"publish","type":"post","link":"https:\/\/gregoryderville.com\/index.php\/2022\/10\/28\/le-chou-petai-lun-de-mes-choux-preferes\/","title":{"rendered":"Le chou Petsa\u00ef, l&rsquo;un de mes choux pr\u00e9f\u00e9r\u00e9s"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le commerce, le chou petsa\u00ef est g\u00e9n\u00e9ralement vendu sous l&rsquo;appellation \u00ab\u00a0chou chinois\u00a0\u00bb, dans une vari\u00e9t\u00e9 plus allong\u00e9e, et d\u00e9barrass\u00e9 des feuilles vertes. Personnellement je mange tout, cuit (surtout quand les feuilles ont \u00e9t\u00e9 attaqu\u00e9es par les limaces) ou cru (quand ils sont intacts).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les graines viennent de chez Biaugerme (vari\u00e9t\u00e9 petsai Granaat).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=5867529149937019&amp;set=pcb.5867534983269769&amp;__cft__[0]=AZVbwx65QP2qfOKsKjqL9JAO9COmtmQSPCH6j4BskP7DC-1UOY1t2cyMrnhMiOhUtzR4Zi8bH8aWzMyYs59YV0CDbqdKLNIcZ_cK0rPE7NI3yjU5xm2IIt4NOoBeTlxm0e4e9Ac4HXd8yMdCKHPFmqF26zrse6kFe8wK4FlRSx9OKw&amp;__tn__=*bH-R\"><\/a><a href=\"https:\/\/www.facebook.com\/photo\/?fbid=5867528563270411&amp;set=pcb.5867534983269769&amp;__cft__[0]=AZVbwx65QP2qfOKsKjqL9JAO9COmtmQSPCH6j4BskP7DC-1UOY1t2cyMrnhMiOhUtzR4Zi8bH8aWzMyYs59YV0CDbqdKLNIcZ_cK0rPE7NI3yjU5xm2IIt4NOoBeTlxm0e4e9Ac4HXd8yMdCKHPFmqF26zrse6kFe8wK4FlRSx9OKw&amp;__tn__=*bH-R\"><\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"737\" data-id=\"5382\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1-1024x737.jpg\" alt=\"\" class=\"wp-image-5382\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1-1024x737.jpg 1024w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1-300x216.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1-768x553.jpg 768w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1-1536x1106.jpg 1536w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1-825x594.jpg 825w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1-1389x1000.jpg 1389w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1-600x432.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1-400x288.jpg 400w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-1.jpg 1979w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5383\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2-1024x683.jpg\" alt=\"\" class=\"wp-image-5383\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2-1024x683.jpg 1024w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2-300x200.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2-768x512.jpg 768w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2-1536x1024.jpg 1536w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2-825x550.jpg 825w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2-1500x1000.jpg 1500w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2-600x400.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2-400x267.jpg 400w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-2.jpg 1773w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4-1024x683.jpg\" alt=\"\" class=\"wp-image-5384\" style=\"width:610px;height:auto\" srcset=\"https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4-1024x683.jpg 1024w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4-300x200.jpg 300w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4-768x512.jpg 768w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4-1536x1024.jpg 1536w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4-825x550.jpg 825w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4-1500x1000.jpg 1500w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4-600x400.jpg 600w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4-400x267.jpg 400w, https:\/\/gregoryderville.com\/wp-content\/uploads\/2025\/02\/petsai-4.jpg 1773w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID5380\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"5380\"\n         id=\"da-reactions-slot-post-5380\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans le commerce, le chou petsa\u00ef est g\u00e9n\u00e9ralement vendu sous l&rsquo;appellation \u00ab\u00a0chou chinois\u00a0\u00bb, dans une vari\u00e9t\u00e9 plus allong\u00e9e, et d\u00e9barrass\u00e9 des feuilles vertes. Personnellement je mange tout, cuit (surtout quand&hellip;<a href=\"https:\/\/gregoryderville.com\/index.php\/2022\/10\/28\/le-chou-petai-lun-de-mes-choux-preferes\/\" class=\"more-link\"><span class=\"more-button\">Continue reading<span class=\"screen-reader-text\">Le chou Petsa\u00ef, l&rsquo;un de mes choux pr\u00e9f\u00e9r\u00e9s<\/span><\/span><\/a><\/p>\n<!-- templates\/buttons-placeholder.php -->\n<div class=\"da-reactions-outer TpostID5380\">\n\t    <div class=\"da-reactions-data da-reactions-container-async center\"\n         data-type=\"post\"\n         data-id=\"5380\"\n         id=\"da-reactions-slot-post-5380\">\n        <div class=\"da-reactions-exposed\">\n\t\t\t<img src=\"https:\/\/gregoryderville.com\/wp-content\/plugins\/da-reactions\/assets\/dist\/loading.svg\" alt=\"Loading spinner\" width=\"64\" height=\"64\" \/>\n        <\/div>\n    <\/div>\n<\/div>\n","protected":false},"author":1,"featured_media":5381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84],"tags":[117,651,72],"class_list":["post-5380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jardin","tag-alimentation","tag-legumes","tag-recoltes"],"_links":{"self":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/5380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/comments?post=5380"}],"version-history":[{"count":2,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/5380\/revisions"}],"predecessor-version":[{"id":5414,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/posts\/5380\/revisions\/5414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media\/5381"}],"wp:attachment":[{"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/media?parent=5380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/categories?post=5380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gregoryderville.com\/index.php\/wp-json\/wp\/v2\/tags?post=5380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}